{"id":2731,"date":"2022-06-27T16:58:22","date_gmt":"2022-06-27T14:58:22","guid":{"rendered":"https:\/\/www.efaflex.com\/?page_id=2731"},"modified":"2025-10-06T09:58:58","modified_gmt":"2025-10-06T07:58:58","slug":"wartung-pruefung","status":"publish","type":"page","link":"https:\/\/www.efaflex.com\/de\/service\/service-deutschland\/wartung-pruefung\/","title":{"rendered":"Wartung &amp; Pr\u00fcfung"},"content":{"rendered":"\n\n<div id=\"breadcrump-block_16287b362cbf1ce6c9d2f530e749d232\" class=\"inner\">\n        <nav class=\"breadcrumb\"><a href=\"https:\/\/www.efaflex.com\/de\/\">Startseite<\/a> \/ <span class=\"current-page\">Seite<\/span><\/nav>    <\/div>\n\n\n<div style=\"height:150px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n<div id=\"textmodul-3-spalten-block_f96ccc3c24315bcc1a769a6507b271d7\" class=\"textmodul-3-spalten\">\n    <div class=\"inner\">\n        <div class=\"custom-flex-box\">\n                            <h1 class=\"flex-box-thirty break headline-two\">Wartung &amp; Pr\u00fcfung.<\/h1>                        <div class=\"flex-box-thirty\"><p>EFAFLEX Tore erf\u00fcllen oft 24 Stunden am Tag, 7 Tage die Woche und 365 Tage im Jahr allerh\u00f6chste Anspr\u00fcche in Sachen Leistung, Funktionalit\u00e4t und Qualit\u00e4t. Damit dies zuverl\u00e4ssig und dauerhaft so bleibt, sind regelm\u00e4\u00dfige Wartung und Pr\u00fcfung erforderlich.<\/p>\n<p>Wir f\u00fchren Wartungen und Pr\u00fcfungen auch f\u00fcr Toranlagen anderer Hersteller durch. Schreiben Sie uns gerne per Mail<a href=\"mailto:service@efaflex.com\"> <span class=\"highlighted\">service@efaflex.com<\/span> <\/a>oder nehmen telefonisch mit uns Kontakt auf <a href=\"tel:+49876582555\"><span class=\"highlighted\">+49 8765 82 555<\/span><\/a>.<\/p>\n<\/div>\n            <div class=\"flex-box-thirty\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"bild-text-modul-links-rechts-block_a3f4288d382b26b58ff526563739ce52\" class=\"bild-text-modul-container\">\n    <div class=\"inner\">\n                                                                                        <div id=\"\" class=\"bild-text-modul-links bild-text-modul\">\n                                <div class=\"custom-flex-box\">\n                                    <div class=\"flex-box-sixty bild-container\">\n                                                                                                                                                                                                                                                                                        <img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.efaflex.com\/wp-content\/uploads\/2024\/01\/7I2A7371.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.efaflex.com\/wp-content\/uploads\/2024\/01\/7I2A7371.jpg 1920w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2024\/01\/7I2A7371-300x200.jpg 300w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2024\/01\/7I2A7371-768x512.jpg 768w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2024\/01\/7I2A7371-1024x683.jpg 1024w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2024\/01\/7I2A7371-1536x1024.jpg 1536w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2024\/01\/7I2A7371-382x254.jpg 382w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>                                                                                                                                                                        <\/div>\n\n                                    <div class=\"flex-box-fourty text-container\">\n                                        <div class=\"text-container-flex\">\n                                            <div class=\"text-inner\">\n                                                                                                                                                            <div class=\"text-left-border\">\n                                                            <div class=\"text-cut\">\n                                                                \n\n                                                                                                                                          <h2 class=\"headline-two\">Wartungsvertrag.<\/h2>                                                                   \n\n                                                                <p class=\"normal-font\"><p>Um die volle Einsatzf\u00e4higkeit Ihres Tores zu gew\u00e4hrleisten, ist ein regelm\u00e4\u00dfiger Service unerl\u00e4sslich. Nur so k\u00f6nnen auf Dauer Verschlei\u00dfsch\u00e4den und die daraus resultierenden Folgekosten vermieden werden. Deshalb bietet Ihnen EFAFLEX individuelle, ganz auf Ihren Bedarf zugeschnittene Wartungspakete f\u00fcr Tore und T\u00fcren aller Hersteller.<\/p>\n<\/p>\n                                                            <\/div>\n                                                            <div class=\"button-box\">\n                                                                                                                                                                                                                                                              <\/div>\n                                                        <\/div>\n                                                                                                                                                <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\n                                    \n            \n\n                    \n                                    \n                            <div id=\"\" class=\"bild-text-modul-rechts bild-text-modul\">\n                                <div class=\"custom-flex-box\">\n                                    <div class=\"flex-box-fourty text-container\">\n                                        <div class=\"text-container-flex\">\n                                            <div class=\"text-inner\">\n\n                                                                                                                                                            <div class=\"text-left-border\">\n                                                            <div class=\"text-cut\">\n                                                                \n\n                                                                                                                                    <h2 class=\"headline-two\">Unterst\u00fctzung <br \/>\r\nBetreiberpflicht.<\/h2>                                                                \n\n                                                                <p class=\"normal-font full-text\"><p>Mit Ihrem ma\u00dfgeschneiderten EFAFLEX-Wartungsvertrag inklusive Sachkundigenpr\u00fcfung erf\u00fcllen Sie alle jeweils g\u00fcltigen Normen und Pflichten. Die vom Gesetzgeber turnusm\u00e4\u00dfig vorgegebene elektrische Pr\u00fcfung findet dabei ebenfalls Ber\u00fccksichtigung.<\/p>\n<\/p>\n\n                                                            <\/div>\n                                                            <div class=\"button-box\">\n                                                                                                                                \n                                                                                                                                                                                                                                                                <\/div>\n                                                        <\/div>\n                                                                                                    \n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"flex-box-sixty bild-container\">\n                                                                                                                                                                                                                                                                                        <img decoding=\"async\" width=\"923\" height=\"556\" src=\"https:\/\/www.efaflex.com\/wp-content\/uploads\/2022\/07\/Digitales_Tor_Tablet_A3-1-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.efaflex.com\/wp-content\/uploads\/2022\/07\/Digitales_Tor_Tablet_A3-1-2.jpg 923w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2022\/07\/Digitales_Tor_Tablet_A3-1-2-300x181.jpg 300w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2022\/07\/Digitales_Tor_Tablet_A3-1-2-768x463.jpg 768w\" sizes=\"(max-width: 923px) 100vw, 923px\" \/>                                                                                                                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                                    \n            \n\n                                                                                    <div id=\"\" class=\"bild-text-modul-links bild-text-modul\">\n                                <div class=\"custom-flex-box\">\n                                    <div class=\"flex-box-sixty bild-container\">\n                                                                                                                                                                                                                                                                                        <img decoding=\"async\" width=\"923\" height=\"556\" src=\"https:\/\/www.efaflex.com\/wp-content\/uploads\/2022\/07\/Digitales_Tor_Tablet_A3-2-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.efaflex.com\/wp-content\/uploads\/2022\/07\/Digitales_Tor_Tablet_A3-2-3.jpg 923w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2022\/07\/Digitales_Tor_Tablet_A3-2-3-300x181.jpg 300w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2022\/07\/Digitales_Tor_Tablet_A3-2-3-768x463.jpg 768w\" sizes=\"(max-width: 923px) 100vw, 923px\" \/>                                                                                                                                                                        <\/div>\n\n                                    <div class=\"flex-box-fourty text-container\">\n                                        <div class=\"text-container-flex\">\n                                            <div class=\"text-inner\">\n                                                                                                                                                            <div class=\"text-left-border\">\n                                                            <div class=\"text-cut\">\n                                                                \n\n                                                                                                                                          <h2 class=\"headline-two\">Termin-Service.<\/h2>                                                                   \n\n                                                                <p class=\"normal-font\"><p>Durch unsere automatisierte Terminkoordinierung garantieren wir die Einhaltung der Pr\u00fcf- und Wartungsintervalle. So ist die Erf\u00fcllung aller gesetzlichen Fristen gew\u00e4hrleistet.<\/p>\n<\/p>\n                                                            <\/div>\n                                                            <div class=\"button-box\">\n                                                                                                                                                                                                                                                              <\/div>\n                                                        <\/div>\n                                                                                                                                                <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\n                                    \n            \n\n                    \n                                    \n                            <div id=\"\" class=\"bild-text-modul-rechts bild-text-modul\">\n                                <div class=\"custom-flex-box\">\n                                    <div class=\"flex-box-fourty text-container\">\n                                        <div class=\"text-container-flex\">\n                                            <div class=\"text-inner\">\n\n                                                                                                                                                            <div class=\"text-left-border\">\n                                                            <div class=\"text-cut\">\n                                                                \n\n                                                                                                                                    <h2 class=\"headline-two\">Beratung &amp;<br \/>\r\nBestandsaufnahme.<\/h2>                                                                \n\n                                                                <p class=\"normal-font full-text\"><p>Zur individuellen Beratung inklusive Bestandsaufnahme bei Ihnen vor Ort steht Ihr zust\u00e4ndiger Serviceberater gerne zur Verf\u00fcgung.<\/p>\n<\/p>\n\n                                                            <\/div>\n                                                            <div class=\"button-box\">\n                                                                                                                                \n                                                                                                                                                                                                                                                                <\/div>\n                                                        <\/div>\n                                                                                                    \n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"flex-box-sixty bild-container\">\n                                                                                                                                                                                                                                                                                        <img decoding=\"async\" width=\"1920\" height=\"1491\" src=\"https:\/\/www.efaflex.com\/wp-content\/uploads\/2025\/10\/service-efaflex-beratung.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.efaflex.com\/wp-content\/uploads\/2025\/10\/service-efaflex-beratung.jpg 1920w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2025\/10\/service-efaflex-beratung-300x233.jpg 300w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2025\/10\/service-efaflex-beratung-768x596.jpg 768w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2025\/10\/service-efaflex-beratung-1024x795.jpg 1024w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2025\/10\/service-efaflex-beratung-1536x1193.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>                                                                                                                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                                    \n            \n\n        \n\n\n        <\/div>\n<\/div>\n\n<style>\n    .bild-text-modul {\n        scroll-margin-top: 143px;\n    }\n<\/style>\n\n\n<div style=\"height:200px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n\n<div     class=\"ansprechpartner-suche-container plz-schnellsuche\">\n    <div class=\"inner\">\n        <div class=\"flex-box\">\n            <div class=\"left-box\">\n                                                            <h2>Schnell zum <br \/>\r\nrichtigen <br \/>\r\nAnsprechpartner:<\/h2>\n                        <input id=\"postalsearch\" type=\"search\" placeholder=\"Postleitzahl\"\n                               maxlength=\"5\">\n                        <div class=\"button-area\">\n                            <a id=\"loadmorebutton\"\n                               class=\"load-more-button\">Jetzt suchen<\/a>\n                        <\/div>\n                                                <\/div>\n            <div class=\"right-box\">\n                                                                    <img decoding=\"async\" width=\"400\" height=\"542\" src=\"https:\/\/www.efaflex.com\/wp-content\/uploads\/2022\/07\/Group.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.efaflex.com\/wp-content\/uploads\/2022\/07\/Group.png 400w, https:\/\/www.efaflex.com\/wp-content\/uploads\/2022\/07\/Group-221x300.png 221w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>                            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n\n        <div class=\"inner\">\n            <div class=\"zweispaltig-bild-text-modul custom-flex-box\">\n                <h2 class=\"standhl\" style=\"display:none;\">Service<\/h2>\n            <\/div>\n        <\/div>\n\n        <div class=\"inner\">\n            <div class=\"standorte_plz custom-flex-box\">\n                                        <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"84000\",\"bis\":\"84109\"},{\"von\":\"84120\",\"bis\":\"84189\"},{\"von\":\"84300\",\"bis\":\"84389\"},{\"von\":\"85000\",\"bis\":\"85044\"},{\"von\":\"85046\",\"bis\":\"85139\"},{\"von\":\"85260\",\"bis\":\"85469\"},{\"von\":\"93000\",\"bis\":\"93109\"},{\"von\":\"93120\",\"bis\":\"93199\"},{\"von\":\"93300\",\"bis\":\"93359\"},{\"von\":\"93400\",\"bis\":\"93499\"},{\"von\":\"94000\",\"bis\":\"94169\"},{\"von\":\"94200\",\"bis\":\"94269\"},{\"von\":\"94300\",\"bis\":\"94379\"},{\"von\":\"94400\",\"bis\":\"94579\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582444\">+49876582444<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.bb@efaflex.com\">service.bb@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"73470\",\"bis\":\"73499\"},{\"von\":\"74000\",\"bis\":\"74259\"},{\"von\":\"74550\",\"bis\":\"74679\"},{\"von\":\"74700\",\"bis\":\"74749\"},{\"von\":\"90000\",\"bis\":\"90619\"},{\"von\":\"90700\",\"bis\":\"90769\"},{\"von\":\"91100\",\"bis\":\"91249\"},{\"von\":\"91400\",\"bis\":\"91489\"},{\"von\":\"91500\",\"bis\":\"91639\"},{\"von\":\"91700\",\"bis\":\"91809\"},{\"von\":\"92200\",\"bis\":\"92289\"},{\"von\":\"92300\",\"bis\":\"92369\"},{\"von\":\"92400\",\"bis\":\"92449\"},{\"von\":\"92500\",\"bis\":\"92559\"},{\"von\":\"92600\",\"bis\":\"92729\"},{\"von\":\"97860\",\"bis\":\"97999\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582444\">+49876582444<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.bb@efaflex.com\">service.bb@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"91000\",\"bis\":\"91099\"},{\"von\":\"91250\",\"bis\":\"91369\"},{\"von\":\"95000\",\"bis\":\"95239\"},{\"von\":\"95300\",\"bis\":\"95369\"},{\"von\":\"95400\",\"bis\":\"95519\"},{\"von\":\"95600\",\"bis\":\"95709\"},{\"von\":\"96000\",\"bis\":\"96279\"},{\"von\":\"96300\",\"bis\":\"96369\"},{\"von\":\"96400\",\"bis\":\"96489\"},{\"von\":\"97000\",\"bis\":\"97359\"},{\"von\":\"97400\",\"bis\":\"97539\"},{\"von\":\"97600\",\"bis\":\"97859\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582444\">+49876582444<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.bb@efaflex.com\">service.bb@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"80001\",\"bis\":\"80999\"},{\"von\":\"81201\",\"bis\":\"81249\"},{\"von\":\"81301\",\"bis\":\"81379\"},{\"von\":\"81451\",\"bis\":\"81479\"},{\"von\":\"81501\",\"bis\":\"81549\"},{\"von\":\"81601\",\"bis\":\"81679\"},{\"von\":\"81701\",\"bis\":\"81739\"},{\"von\":\"81801\",\"bis\":\"81829\"},{\"von\":\"81901\",\"bis\":\"81929\"},{\"von\":\"82000\",\"bis\":\"82069\"},{\"von\":\"82100\",\"bis\":\"82239\"},{\"von\":\"82300\",\"bis\":\"82549\"},{\"von\":\"83000\",\"bis\":\"83139\"},{\"von\":\"83200\",\"bis\":\"83489\"},{\"von\":\"83500\",\"bis\":\"83569\"},{\"von\":\"83600\",\"bis\":\"83739\"},{\"von\":\"84400\",\"bis\":\"84579\"},{\"von\":\"85200\",\"bis\":\"85259\"},{\"von\":\"85500\",\"bis\":\"85669\"},{\"von\":\"85700\",\"bis\":\"85779\"},{\"von\":\"85045\",\"bis\":\"85045\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582444\">+49876582444<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.bb@efaflex.com\">service.bb@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"82240\",\"bis\":\"82299\"},{\"von\":\"86000\",\"bis\":\"86579\"},{\"von\":\"86600\",\"bis\":\"86759\"},{\"von\":\"86800\",\"bis\":\"86949\"},{\"von\":\"86950\",\"bis\":\"86989\"},{\"von\":\"87400\",\"bis\":\"87789\"},{\"von\":\"88100\",\"bis\":\"88179\"},{\"von\":\"88290\",\"bis\":\"88319\"},{\"von\":\"89200\",\"bis\":\"89369\"},{\"von\":\"89400\",\"bis\":\"89449\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582444\">+49876582444<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.bb@efaflex.com\">service.bb@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"10000\",\"bis\":\"10999\"},{\"von\":\"12000\",\"bis\":\"12689\"},{\"von\":\"13000\",\"bis\":\"13689\"},{\"von\":\"14000\",\"bis\":\"14199\"},{\"von\":\"14400\",\"bis\":\"14559\"},{\"von\":\"14600\",\"bis\":\"14669\"},{\"von\":\"14700\",\"bis\":\"14799\"},{\"von\":\"14800\",\"bis\":\"14829\"},{\"von\":\"14900\",\"bis\":\"14929\"},{\"von\":\"14930\",\"bis\":\"14979\"},{\"von\":\"15200\",\"bis\":\"15379\"},{\"von\":\"15500\",\"bis\":\"15569\"},{\"von\":\"15700\",\"bis\":\"15759\"},{\"von\":\"15800\",\"bis\":\"15899\"},{\"von\":\"15900\",\"bis\":\"15939\"},{\"von\":\"16200\",\"bis\":\"16359\"},{\"von\":\"16500\",\"bis\":\"16569\"},{\"von\":\"16720\",\"bis\":\"16869\"},{\"von\":\"16900\",\"bis\":\"16949\"},{\"von\":\"17000\",\"bis\":\"17509\"},{\"von\":\"18000\",\"bis\":\"18379\"},{\"von\":\"18400\",\"bis\":\"18469\"},{\"von\":\"18500\",\"bis\":\"18609\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung Nord-Ost<br>\n                                                                                                15366 Neuenhagen b. Berlin                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+493342213410\">+493342213410<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.be@efaflex.com\">service.be@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"51530\",\"bis\":\"51599\"},{\"von\":\"53000\",\"bis\":\"53359\"},{\"von\":\"53400\",\"bis\":\"53509\"},{\"von\":\"53510\",\"bis\":\"53539\"},{\"von\":\"53540\",\"bis\":\"53639\"},{\"von\":\"53700\",\"bis\":\"53859\"},{\"von\":\"53860\",\"bis\":\"53949\"},{\"von\":\"57000\",\"bis\":\"57399\"},{\"von\":\"57440\",\"bis\":\"57489\"},{\"von\":\"57500\",\"bis\":\"57589\"},{\"von\":\"57600\",\"bis\":\"57649\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                40721 Hilden                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+492103509311\">+492103509311<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.hi@efaflex.com\">service.hi@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"40000\",\"bis\":\"40789\"},{\"von\":\"40800\",\"bis\":\"40889\"},{\"von\":\"41000\",\"bis\":\"41379\"},{\"von\":\"41400\",\"bis\":\"41569\"},{\"von\":\"41700\",\"bis\":\"41759\"},{\"von\":\"41800\",\"bis\":\"41849\"},{\"von\":\"42500\",\"bis\":\"42579\"},{\"von\":\"45000\",\"bis\":\"45359\"},{\"von\":\"45400\",\"bis\":\"45489\"},{\"von\":\"45600\",\"bis\":\"45779\"},{\"von\":\"45800\",\"bis\":\"45899\"},{\"von\":\"45950\",\"bis\":\"45969\"},{\"von\":\"46000\",\"bis\":\"46149\"},{\"von\":\"46200\",\"bis\":\"46289\"},{\"von\":\"46420\",\"bis\":\"46569\"},{\"von\":\"47000\",\"bis\":\"47279\"},{\"von\":\"47400\",\"bis\":\"47669\"},{\"von\":\"47700\",\"bis\":\"47929\"},{\"von\":\"50100\",\"bis\":\"50189\"},{\"von\":\"50200\",\"bis\":\"50259\"},{\"von\":\"50300\",\"bis\":\"50389\"},{\"von\":\"50440\",\"bis\":\"50999\"},{\"von\":\"52000\",\"bis\":\"52159\"},{\"von\":\"52200\",\"bis\":\"52249\"},{\"von\":\"52300\",\"bis\":\"52539\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                40721 Hilden                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+492103509311\">+492103509311<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.hi@efaflex.com\">service.hi@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"34400\",\"bis\":\"34439\"},{\"von\":\"34440\",\"bis\":\"34519\"},{\"von\":\"34520\",\"bis\":\"34639\"},{\"von\":\"35000\",\"bis\":\"35119\"},{\"von\":\"35240\",\"bis\":\"35289\"},{\"von\":\"35300\",\"bis\":\"35469\"},{\"von\":\"35500\",\"bis\":\"35649\"},{\"von\":\"36000\",\"bis\":\"36399\"},{\"von\":\"37200\",\"bis\":\"37299\"},{\"von\":\"55000\",\"bis\":\"55299\"},{\"von\":\"60000\",\"bis\":\"60599\"},{\"von\":\"61100\",\"bis\":\"61389\"},{\"von\":\"61400\",\"bis\":\"61479\"},{\"von\":\"63000\",\"bis\":\"63179\"},{\"von\":\"63200\",\"bis\":\"63329\"},{\"von\":\"63400\",\"bis\":\"63549\"},{\"von\":\"63550\",\"bis\":\"63639\"},{\"von\":\"63640\",\"bis\":\"63699\"},{\"von\":\"63700\",\"bis\":\"63939\"},{\"von\":\"64200\",\"bis\":\"64409\"},{\"von\":\"64500\",\"bis\":\"64589\"},{\"von\":\"64600\",\"bis\":\"64689\"},{\"von\":\"64700\",\"bis\":\"64759\"},{\"von\":\"64800\",\"bis\":\"64859\"},{\"von\":\"65000\",\"bis\":\"65239\"},{\"von\":\"65300\",\"bis\":\"65479\"},{\"von\":\"65500\",\"bis\":\"65529\"},{\"von\":\"65700\",\"bis\":\"65939\"},{\"von\":\"67500\",\"bis\":\"67599\"},{\"von\":\"68600\",\"bis\":\"68649\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                65479 Raunheim                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+496142991818\">+496142991818<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.rh@efaflex.com\">service.rh@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"54200\",\"bis\":\"54349\"},{\"von\":\"54400\",\"bis\":\"54499\"},{\"von\":\"55380\",\"bis\":\"55629\"},{\"von\":\"55700\",\"bis\":\"55779\"},{\"von\":\"66000\",\"bis\":\"66999\"},{\"von\":\"67000\",\"bis\":\"67169\"},{\"von\":\"67200\",\"bis\":\"67379\"},{\"von\":\"67400\",\"bis\":\"67489\"},{\"von\":\"67600\",\"bis\":\"67759\"},{\"von\":\"67800\",\"bis\":\"67829\"},{\"von\":\"68000\",\"bis\":\"68549\"},{\"von\":\"68700\",\"bis\":\"68809\"},{\"von\":\"69000\",\"bis\":\"69259\"},{\"von\":\"69400\",\"bis\":\"69519\"},{\"von\":\"74800\",\"bis\":\"74939\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                65479 Raunheim                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+496142991818\">+496142991818<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.rh@efaflex.com\">service.rh@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"35200\",\"bis\":\"35239\"},{\"von\":\"35660\",\"bis\":\"35799\"},{\"von\":\"54500\",\"bis\":\"54689\"},{\"von\":\"56000\",\"bis\":\"56379\"},{\"von\":\"56400\",\"bis\":\"56479\"},{\"von\":\"56500\",\"bis\":\"56659\"},{\"von\":\"56700\",\"bis\":\"56769\"},{\"von\":\"56800\",\"bis\":\"56869\"},{\"von\":\"65530\",\"bis\":\"65629\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                65479 Raunheim                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+496142991818\">+496142991818<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.rh@efaflex.com\">service.rh@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"70000\",\"bis\":\"70629\"},{\"von\":\"70700\",\"bis\":\"70839\"},{\"von\":\"71000\",\"bis\":\"71159\"},{\"von\":\"71200\",\"bis\":\"71409\"},{\"von\":\"71500\",\"bis\":\"71579\"},{\"von\":\"71600\",\"bis\":\"71739\"},{\"von\":\"72000\",\"bis\":\"72149\"},{\"von\":\"72370\",\"bis\":\"72419\"},{\"von\":\"72540\",\"bis\":\"72589\"},{\"von\":\"72600\",\"bis\":\"72669\"},{\"von\":\"72700\",\"bis\":\"72829\"},{\"von\":\"73000\",\"bis\":\"73119\"},{\"von\":\"73200\",\"bis\":\"73279\"},{\"von\":\"73300\",\"bis\":\"73349\"},{\"von\":\"73400\",\"bis\":\"73469\"},{\"von\":\"73500\",\"bis\":\"73579\"},{\"von\":\"73600\",\"bis\":\"73669\"},{\"von\":\"73700\",\"bis\":\"73779\"},{\"von\":\"74300\",\"bis\":\"74429\"},{\"von\":\"74500\",\"bis\":\"74549\"},{\"von\":\"75350\",\"bis\":\"75399\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung S\u00fcd-West<br>\n                                                                                                73529 Schw\u00e4bisch Gm\u00fcnd                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+497171874100\">+497171874100<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.bw@efaflex.com\">service.bw@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"72300\",\"bis\":\"72369\"},{\"von\":\"72420\",\"bis\":\"72539\"},{\"von\":\"78000\",\"bis\":\"78089\"},{\"von\":\"78150\",\"bis\":\"78199\"},{\"von\":\"78200\",\"bis\":\"78269\"},{\"von\":\"78300\",\"bis\":\"78359\"},{\"von\":\"78400\",\"bis\":\"78479\"},{\"von\":\"78500\",\"bis\":\"78669\"},{\"von\":\"88000\",\"bis\":\"88099\"},{\"von\":\"88180\",\"bis\":\"88289\"},{\"von\":\"88320\",\"bis\":\"88529\"},{\"von\":\"88600\",\"bis\":\"88719\"},{\"von\":\"89000\",\"bis\":\"89199\"},{\"von\":\"89500\",\"bis\":\"89619\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung S\u00fcd-West<br>\n                                                                                                73529 Schw\u00e4bisch Gm\u00fcnd                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+497171874100\">+497171874100<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.bw@efaflex.com\">service.bw@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"72150\",\"bis\":\"72299\"},{\"von\":\"75000\",\"bis\":\"75059\"},{\"von\":\"75100\",\"bis\":\"75249\"},{\"von\":\"75300\",\"bis\":\"75339\"},{\"von\":\"75400\",\"bis\":\"75449\"},{\"von\":\"76000\",\"bis\":\"76359\"},{\"von\":\"76400\",\"bis\":\"76599\"},{\"von\":\"76600\",\"bis\":\"76779\"},{\"von\":\"76800\",\"bis\":\"76899\"},{\"von\":\"77600\",\"bis\":\"77889\"},{\"von\":\"77900\",\"bis\":\"77979\"},{\"von\":\"78090\",\"bis\":\"78149\"},{\"von\":\"78700\",\"bis\":\"78739\"},{\"von\":\"79000\",\"bis\":\"79429\"},{\"von\":\"79500\",\"bis\":\"79879\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung S\u00fcd-West<br>\n                                                                                                73529 Schw\u00e4bisch Gm\u00fcnd                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+497171874100\">+497171874100<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.bw@efaflex.com\">service.bw@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"04000\",\"bis\":\"04469\"},{\"von\":\"04500\",\"bis\":\"04619\"},{\"von\":\"04640\",\"bis\":\"04689\"},{\"von\":\"04750\",\"bis\":\"04779\"},{\"von\":\"04800\",\"bis\":\"04939\"},{\"von\":\"06000\",\"bis\":\"06139\"},{\"von\":\"06170\",\"bis\":\"06579\"},{\"von\":\"06600\",\"bis\":\"06929\"},{\"von\":\"36400\",\"bis\":\"36469\"},{\"von\":\"37300\",\"bis\":\"37359\"},{\"von\":\"96500\",\"bis\":\"96529\"},{\"von\":\"98500\",\"bis\":\"98749\"},{\"von\":\"99000\",\"bis\":\"99109\"},{\"von\":\"99180\",\"bis\":\"99199\"},{\"von\":\"99300\",\"bis\":\"99339\"},{\"von\":\"99400\",\"bis\":\"99449\"},{\"von\":\"99500\",\"bis\":\"99519\"},{\"von\":\"99600\",\"bis\":\"99639\"},{\"von\":\"99700\",\"bis\":\"99769\"},{\"von\":\"99800\",\"bis\":\"99899\"},{\"von\":\"99940\",\"bis\":\"99999\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung Nord-Ost<br>\n                                                                                                04416 Markkleeberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+493429798770\">+493429798770<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.le@efaflex.com\">service.le@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"01000\",\"bis\":\"01329\"},{\"von\":\"01430\",\"bis\":\"01479\"},{\"von\":\"01550\",\"bis\":\"01859\"},{\"von\":\"01870\",\"bis\":\"01999\"},{\"von\":\"02600\",\"bis\":\"02999\"},{\"von\":\"03000\",\"bis\":\"03259\"},{\"von\":\"04620\",\"bis\":\"04639\"},{\"von\":\"04700\",\"bis\":\"04749\"},{\"von\":\"07300\",\"bis\":\"07429\"},{\"von\":\"07500\",\"bis\":\"07589\"},{\"von\":\"07600\",\"bis\":\"07649\"},{\"von\":\"07700\",\"bis\":\"07779\"},{\"von\":\"07800\",\"bis\":\"07819\"},{\"von\":\"07900\",\"bis\":\"07989\"},{\"von\":\"08000\",\"bis\":\"08069\"},{\"von\":\"08100\",\"bis\":\"08149\"},{\"von\":\"08200\",\"bis\":\"08549\"},{\"von\":\"08600\",\"bis\":\"08609\"},{\"von\":\"08620\",\"bis\":\"08649\"},{\"von\":\"09000\",\"bis\":\"09249\"},{\"von\":\"09300\",\"bis\":\"09669\"}]'>\n                            <span class=\"htitle\">Backoffice<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihre Ansprechpartner zu Anfragen und Bestellungen von Ersatzteilen und Serviceleistungen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                                                    Kundendienstniederlassung Nord-Ost<br>\n                                                                                                04416 Markkleeberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+493429798770\">+493429798770<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:service.le@efaflex.com\">service.le@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"20000\",\"bis\":\"20539\"},{\"von\":\"21000\",\"bis\":\"21279\"},{\"von\":\"21300\",\"bis\":\"21529\"},{\"von\":\"21600\",\"bis\":\"21789\"},{\"von\":\"22000\",\"bis\":\"22889\"},{\"von\":\"22900\",\"bis\":\"22969\"},{\"von\":\"23500\",\"bis\":\"23629\"},{\"von\":\"23660\",\"bis\":\"24259\"},{\"von\":\"24300\",\"bis\":\"24409\"},{\"von\":\"24500\",\"bis\":\"24649\"},{\"von\":\"24750\",\"bis\":\"24999\"},{\"von\":\"25300\",\"bis\":\"25379\"},{\"von\":\"25400\",\"bis\":\"25599\"},{\"von\":\"25690\",\"bis\":\"25999\"}]'>\n                            <span class=\"htitle\">Montageleitung<\/span>\n                                                            <p>\n                                    <strong>\n                                        Bremen EFAFLEX Tortechnik GmbH                                     <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Joschka Schwedler Grau<br>\n                                                                                                                                28719 Bremen                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+4942160608032\">+4942160608032<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:Joschka.Schwedler.Grau@efaflex-hildesheim.de\">Joschka.Schwedler.Grau@efaflex-hildesheim.de<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"26000\",\"bis\":\"26219\"},{\"von\":\"26300\",\"bis\":\"26969\"},{\"von\":\"27200\",\"bis\":\"27639\"},{\"von\":\"27700\",\"bis\":\"27809\"},{\"von\":\"28000\",\"bis\":\"28359\"},{\"von\":\"28700\",\"bis\":\"28879\"},{\"von\":\"48455\",\"bis\":\"48476\"},{\"von\":\"48478\",\"bis\":\"48484\"},{\"von\":\"48486\",\"bis\":\"48492\"},{\"von\":\"48497\",\"bis\":\"48531\"},{\"von\":\"49153\",\"bis\":\"49162\"},{\"von\":\"49164\",\"bis\":\"49169\"},{\"von\":\"49177\",\"bis\":\"49185\"},{\"von\":\"49329\",\"bis\":\"49329\"},{\"von\":\"49340\",\"bis\":\"49476\"},{\"von\":\"49550\",\"bis\":\"49563\"},{\"von\":\"49566\",\"bis\":\"49585\"},{\"von\":\"49587\",\"bis\":\"49849\"}]'>\n                            <span class=\"htitle\">Montageleitung<\/span>\n                                                            <p>\n                                    <strong>\n                                        Bremen EFAFLEX Tortechnik GmbH                                     <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Volker Mechau<br>\n                                                                                                                                28719 Bremen                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+4942160608026\">+4942160608026<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:volker.mechau@efaflex-hildesheim.de \">volker.mechau@efaflex-hildesheim.de <\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"30000\",\"bis\":\"30989\"},{\"von\":\"31500\",\"bis\":\"31869\"},{\"von\":\"32000\",\"bis\":\"32119\"},{\"von\":\"32121\",\"bis\":\"32139\"},{\"von\":\"32210\",\"bis\":\"32288\"},{\"von\":\"32290\",\"bis\":\"32311\"},{\"von\":\"32313\",\"bis\":\"32338\"},{\"von\":\"32340\",\"bis\":\"32350\"},{\"von\":\"32352\",\"bis\":\"32360\"},{\"von\":\"32362\",\"bis\":\"32368\"},{\"von\":\"32370\",\"bis\":\"32479\"},{\"von\":\"32500\",\"bis\":\"32608\"},{\"von\":\"32630\",\"bis\":\"32839\"},{\"von\":\"33000\",\"bis\":\"33189\"},{\"von\":\"33240\",\"bis\":\"33329\"},{\"von\":\"34000\",\"bis\":\"34399\"},{\"von\":\"59240\",\"bis\":\"59268\"},{\"von\":\"59470\",\"bis\":\"59493\"},{\"von\":\"59495\",\"bis\":\"59504\"},{\"von\":\"59506\",\"bis\":\"59509\"},{\"von\":\"59511\",\"bis\":\"59513\"},{\"von\":\"59515\",\"bis\":\"59518\"},{\"von\":\"59520\",\"bis\":\"59551\"},{\"von\":\"59553\",\"bis\":\"59554\"},{\"von\":\"59559\",\"bis\":\"59580\"},{\"von\":\"59582\",\"bis\":\"59589\"},{\"von\":\"59591\",\"bis\":\"59596\"},{\"von\":\"59598\",\"bis\":\"59601\"},{\"von\":\"59603\",\"bis\":\"59699\"}]'>\n                            <span class=\"htitle\">Montageleitung<\/span>\n                                                            <p>\n                                    <strong>\n                                        Harsum EFAFLEX Tortechnik GmbH                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Frank Behrens<br>\n                                                                                                                                31177 Harsum                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+495127214830\">+495127214830<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:frank.behrens@efaflex-hildesheim.de \">frank.behrens@efaflex-hildesheim.de <\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"19000\",\"bis\":\"19089\"},{\"von\":\"19200\",\"bis\":\"19419\"},{\"von\":\"29200\",\"bis\":\"29419\"},{\"von\":\"29430\",\"bis\":\"29649\"},{\"von\":\"29650\",\"bis\":\"29699\"},{\"von\":\"31000\",\"bis\":\"31319\"},{\"von\":\"37000\",\"bis\":\"37199\"},{\"von\":\"37400\",\"bis\":\"37589\"},{\"von\":\"38000\",\"bis\":\"38179\"},{\"von\":\"38200\",\"bis\":\"38489\"},{\"von\":\"38500\",\"bis\":\"38559\"},{\"von\":\"38600\",\"bis\":\"38729\"},{\"von\":\"38800\",\"bis\":\"39139\"},{\"von\":\"39150\",\"bis\":\"39179\"},{\"von\":\"39200\",\"bis\":\"39449\"},{\"von\":\"39510\",\"bis\":\"39539\"},{\"von\":\"39550\",\"bis\":\"39649\"}]'>\n                            <span class=\"htitle\">Montageleitung<\/span>\n                                                            <p>\n                                    <strong>\n                                        Harsum EFAFLEX Tortechnik GmbH                                     <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Frau Katrin Breitbarth<br>\n                                                                                                                                31177 Harsum                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+495127214823\">+495127214823<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:katrin.breitbarth@efaflex-hildesheim.de \">katrin.breitbarth@efaflex-hildesheim.de <\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"32289\",\"bis\":\"32289\"},{\"von\":\"32312\",\"bis\":\"32312\"},{\"von\":\"32339\",\"bis\":\"32339\"},{\"von\":\"32351\",\"bis\":\"32351\"},{\"von\":\"32361\",\"bis\":\"32361\"},{\"von\":\"32369\",\"bis\":\"32369\"},{\"von\":\"32609\",\"bis\":\"32609\"},{\"von\":\"33330\",\"bis\":\"33999\"},{\"von\":\"48000\",\"bis\":\"48248\"},{\"von\":\"48250\",\"bis\":\"48267\"},{\"von\":\"48269\",\"bis\":\"48281\"},{\"von\":\"48283\",\"bis\":\"48300\"},{\"von\":\"48302\",\"bis\":\"48307\"},{\"von\":\"48309\",\"bis\":\"48328\"},{\"von\":\"48330\",\"bis\":\"48340\"},{\"von\":\"48342\",\"bis\":\"48355\"},{\"von\":\"48357\",\"bis\":\"48365\"},{\"von\":\"48367\",\"bis\":\"48428\"},{\"von\":\"48430\",\"bis\":\"48430\"},{\"von\":\"48433\",\"bis\":\"48454\"},{\"von\":\"49124\",\"bis\":\"49124\"},{\"von\":\"49143\",\"bis\":\"49143\"},{\"von\":\"49152\",\"bis\":\"49152\"},{\"von\":\"49170\",\"bis\":\"49176\"},{\"von\":\"49186\",\"bis\":\"49190\"},{\"von\":\"49192\",\"bis\":\"49328\"},{\"von\":\"49478\",\"bis\":\"49478\"},{\"von\":\"49480\",\"bis\":\"49491\"},{\"von\":\"49493\",\"bis\":\"49496\"},{\"von\":\"49498\",\"bis\":\"49503\"},{\"von\":\"49505\",\"bis\":\"49544\"},{\"von\":\"49546\",\"bis\":\"49549\"},{\"von\":\"59269\",\"bis\":\"59399\"},{\"von\":\"59494\",\"bis\":\"59494\"},{\"von\":\"59505\",\"bis\":\"59505\"},{\"von\":\"59510\",\"bis\":\"59510\"},{\"von\":\"59514\",\"bis\":\"59514\"},{\"von\":\"59519\",\"bis\":\"59519\"},{\"von\":\"59552\",\"bis\":\"59552\"},{\"von\":\"59555\",\"bis\":\"59558\"},{\"von\":\"59581\",\"bis\":\"59581\"},{\"von\":\"59590\",\"bis\":\"59590\"},{\"von\":\"59597\",\"bis\":\"59597\"},{\"von\":\"59602\",\"bis\":\"59602\"}]'>\n                            <span class=\"htitle\">Montageleitung<\/span>\n                                                            <p>\n                                    <strong>\n                                        Osnabr\u00fcck EFAFLEX Tortechnik GmbH                                     <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Georg Musial<br>\n                                                                                                                                49205 Hasbergen                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+4954058088720\">+4954058088720<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:georg.musial@efaflex-hildesheim.de \">georg.musial@efaflex-hildesheim.de <\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"46286\",\"bis\":\"46419\"},{\"von\":\"48249\",\"bis\":\"48249\"},{\"von\":\"48268\",\"bis\":\"48268\"},{\"von\":\"48282\",\"bis\":\"48282\"},{\"von\":\"48301\",\"bis\":\"48301\"},{\"von\":\"48308\",\"bis\":\"48308\"},{\"von\":\"48329\",\"bis\":\"48329\"},{\"von\":\"48341\",\"bis\":\"48341\"},{\"von\":\"48356\",\"bis\":\"48356\"},{\"von\":\"48366\",\"bis\":\"48366\"},{\"von\":\"48429\",\"bis\":\"48429\"},{\"von\":\"48431\",\"bis\":\"48432\"},{\"von\":\"48477\",\"bis\":\"48477\"},{\"von\":\"48485\",\"bis\":\"48485\"},{\"von\":\"48493\",\"bis\":\"48496\"},{\"von\":\"48532\",\"bis\":\"49151\"},{\"von\":\"49163\",\"bis\":\"49163\"},{\"von\":\"49191\",\"bis\":\"49191\"},{\"von\":\"49477\",\"bis\":\"49477\"},{\"von\":\"49479\",\"bis\":\"49479\"},{\"von\":\"49492\",\"bis\":\"49492\"},{\"von\":\"49497\",\"bis\":\"49497\"},{\"von\":\"49504\",\"bis\":\"49504\"},{\"von\":\"49545\",\"bis\":\"49545\"},{\"von\":\"49565\",\"bis\":\"49565\"},{\"von\":\"49586\",\"bis\":\"49586\"}]'>\n                            <span class=\"htitle\">Montageleitung<\/span>\n                                                            <p>\n                                    <strong>\n                                        Osnabr\u00fcck EFAFLEX Tortechnik GmbH                                     <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Frank Ostermann<br>\n                                                                                                                                49205 Hasbergen                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+4954058088718\">+4954058088718<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:frank.ostermann@efaflex-hildesheim.de\">frank.ostermann@efaflex-hildesheim.de<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"38231\",\"bis\":\"38231\"},{\"von\":\"38468\",\"bis\":\"38468\"},{\"von\":\"30419\",\"bis\":\"30419\"},{\"von\":\"38176\",\"bis\":\"38176\"}]'>\n                            <span class=\"htitle\">Montageleitung<\/span>\n                                                            <p>\n                                    <strong>\n                                        Harsum EFAFLEX Tortechnik GmbH                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Frank Behrens<br>\n                                                                                                                                31177 Harsum                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+495127214830\">+495127214830<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:frank.behrens@efaflex-hildesheim.de \">frank.behrens@efaflex-hildesheim.de <\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"38112\",\"bis\":\"38112\"},{\"von\":\"34123\",\"bis\":\"34123\"},{\"von\":\"34225\",\"bis\":\"34225\"},{\"von\":\"38440\",\"bis\":\"38440\"},{\"von\":\"38436\",\"bis\":\"38436\"}]'>\n                            <span class=\"htitle\">Montageleitung<\/span>\n                                                            <p>\n                                    <strong>\n                                        Harsum EFAFLEX Tortechnik GmbH                                     <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Frau Katrin Breitbarth<br>\n                                                                                                                                31177 Harsum                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+495127214823\">+495127214823<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:katrin.breitbarth@efaflex-hildesheim.de \">katrin.breitbarth@efaflex-hildesheim.de <\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"84000\",\"bis\":\"84109\"},{\"von\":\"84120\",\"bis\":\"84189\"},{\"von\":\"84300\",\"bis\":\"84389\"},{\"von\":\"85000\",\"bis\":\"85044\"},{\"von\":\"85046\",\"bis\":\"85139\"},{\"von\":\"85260\",\"bis\":\"85469\"},{\"von\":\"93000\",\"bis\":\"93109\"},{\"von\":\"93120\",\"bis\":\"93199\"},{\"von\":\"93300\",\"bis\":\"93359\"},{\"von\":\"93400\",\"bis\":\"93499\"},{\"von\":\"94000\",\"bis\":\"94169\"},{\"von\":\"94200\",\"bis\":\"94269\"},{\"von\":\"94300\",\"bis\":\"94379\"},{\"von\":\"94400\",\"bis\":\"94579\"},{\"von\":\"80001\",\"bis\":\"80999\"},{\"von\":\"81201\",\"bis\":\"81249\"},{\"von\":\"81301\",\"bis\":\"81379\"},{\"von\":\"81451\",\"bis\":\"81479\"},{\"von\":\"81501\",\"bis\":\"81549\"},{\"von\":\"81601\",\"bis\":\"81679\"},{\"von\":\"81701\",\"bis\":\"81739\"},{\"von\":\"81801\",\"bis\":\"81829\"},{\"von\":\"81901\",\"bis\":\"81929\"},{\"von\":\"82000\",\"bis\":\"82069\"},{\"von\":\"82100\",\"bis\":\"82239\"},{\"von\":\"82300\",\"bis\":\"82549\"},{\"von\":\"83000\",\"bis\":\"83139\"},{\"von\":\"83200\",\"bis\":\"83489\"},{\"von\":\"83500\",\"bis\":\"83569\"},{\"von\":\"83600\",\"bis\":\"83739\"},{\"von\":\"84400\",\"bis\":\"84579\"},{\"von\":\"85200\",\"bis\":\"85259\"},{\"von\":\"85500\",\"bis\":\"85669\"},{\"von\":\"85700\",\"bis\":\"85779\"},{\"von\":\"85045\",\"bis\":\"85045\"},{\"von\":\"82240\",\"bis\":\"82299\"},{\"von\":\"86000\",\"bis\":\"86579\"},{\"von\":\"86600\",\"bis\":\"86759\"},{\"von\":\"86800\",\"bis\":\"86949\"},{\"von\":\"86950\",\"bis\":\"86989\"},{\"von\":\"87400\",\"bis\":\"87789\"},{\"von\":\"88100\",\"bis\":\"88179\"},{\"von\":\"88290\",\"bis\":\"88319\"},{\"von\":\"89200\",\"bis\":\"89369\"},{\"von\":\"89400\",\"bis\":\"89449\"}]'>\n                            <span class=\"htitle\">Serviceberater<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur individuellen Vor-Ort-Beratung f\u00fcr alle Servicethemen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Enrico Gleitz<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491703731822\">+491703731822<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:enrico.gleitz@efaflex.com\">enrico.gleitz@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"12345\",\"bis\":\"12345\"},{\"von\":\"34400\",\"bis\":\"34439\"},{\"von\":\"34440\",\"bis\":\"34519\"},{\"von\":\"34520\",\"bis\":\"34639\"},{\"von\":\"35000\",\"bis\":\"35119\"},{\"von\":\"35240\",\"bis\":\"35289\"},{\"von\":\"35300\",\"bis\":\"35469\"},{\"von\":\"35500\",\"bis\":\"35649\"},{\"von\":\"36000\",\"bis\":\"36399\"},{\"von\":\"37200\",\"bis\":\"37299\"},{\"von\":\"60000\",\"bis\":\"60599\"},{\"von\":\"61100\",\"bis\":\"61389\"},{\"von\":\"61400\",\"bis\":\"61479\"},{\"von\":\"63151\",\"bis\":\"63179\"},{\"von\":\"63400\",\"bis\":\"63549\"},{\"von\":\"63400\",\"bis\":\"63549\"},{\"von\":\"63550\",\"bis\":\"63599\"},{\"von\":\"63600\",\"bis\":\"63639\"},{\"von\":\"63640\",\"bis\":\"63699\"},{\"von\":\"63700\",\"bis\":\"63776\"},{\"von\":\"63802\",\"bis\":\"63831\"},{\"von\":\"65392\",\"bis\":\"65451\"},{\"von\":\"65500\",\"bis\":\"65529\"},{\"von\":\"65700\",\"bis\":\"65939\"},{\"von\":\"54200\",\"bis\":\"54349\"},{\"von\":\"54400\",\"bis\":\"54499\"},{\"von\":\"55380\",\"bis\":\"55629\"},{\"von\":\"55700\",\"bis\":\"55779\"},{\"von\":\"66000\",\"bis\":\"66999\"},{\"von\":\"67000\",\"bis\":\"67169\"},{\"von\":\"67200\",\"bis\":\"67379\"},{\"von\":\"67400\",\"bis\":\"67489\"},{\"von\":\"67600\",\"bis\":\"67759\"},{\"von\":\"67800\",\"bis\":\"67829\"},{\"von\":\"68000\",\"bis\":\"68549\"},{\"von\":\"68700\",\"bis\":\"68809\"},{\"von\":\"69000\",\"bis\":\"69259\"},{\"von\":\"69400\",\"bis\":\"69519\"},{\"von\":\"74800\",\"bis\":\"74939\"},{\"von\":\"35200\",\"bis\":\"35239\"},{\"von\":\"35660\",\"bis\":\"35799\"},{\"von\":\"54500\",\"bis\":\"54689\"},{\"von\":\"56000\",\"bis\":\"56379\"},{\"von\":\"56400\",\"bis\":\"56479\"},{\"von\":\"56500\",\"bis\":\"56659\"},{\"von\":\"56700\",\"bis\":\"56769\"},{\"von\":\"56800\",\"bis\":\"56869\"},{\"von\":\"65530\",\"bis\":\"65629\"},{\"von\":\"55000\",\"bis\":\"55299\"},{\"von\":\"63076\",\"bis\":\"63150\"},{\"von\":\"63200\",\"bis\":\"63329\"},{\"von\":\"63777\",\"bis\":\"63801\"},{\"von\":\"63832\",\"bis\":\"63939\"},{\"von\":\"64200\",\"bis\":\"64409\"},{\"von\":\"64500\",\"bis\":\"64589\"},{\"von\":\"64600\",\"bis\":\"64689\"},{\"von\":\"64700\",\"bis\":\"64759\"},{\"von\":\"64800\",\"bis\":\"64859\"},{\"von\":\"65000\",\"bis\":\"65239\"},{\"von\":\"65300\",\"bis\":\"65391\"},{\"von\":\"65452\",\"bis\":\"65479\"},{\"von\":\"67500\",\"bis\":\"67599\"},{\"von\":\"68600\",\"bis\":\"68649\"}]'>\n                            <span class=\"htitle\">Serviceberater<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur individuellen Vor-Ort-Beratung f\u00fcr alle Servicethemen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Mario Jung<br>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                65479 Raunheim                            <\/p>\n\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491707985793\">+491707985793<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:mario.jung@efaflex.com\">mario.jung@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"70000\",\"bis\":\"70629\"},{\"von\":\"70700\",\"bis\":\"70839\"},{\"von\":\"71000\",\"bis\":\"71159\"},{\"von\":\"71200\",\"bis\":\"71409\"},{\"von\":\"71500\",\"bis\":\"71579\"},{\"von\":\"71600\",\"bis\":\"71739\"},{\"von\":\"72000\",\"bis\":\"72149\"},{\"von\":\"72370\",\"bis\":\"72419\"},{\"von\":\"72540\",\"bis\":\"72589\"},{\"von\":\"72600\",\"bis\":\"72669\"},{\"von\":\"72700\",\"bis\":\"72829\"},{\"von\":\"73000\",\"bis\":\"73119\"},{\"von\":\"73200\",\"bis\":\"73279\"},{\"von\":\"73300\",\"bis\":\"73349\"},{\"von\":\"73400\",\"bis\":\"73469\"},{\"von\":\"73500\",\"bis\":\"73579\"},{\"von\":\"73600\",\"bis\":\"73669\"},{\"von\":\"73700\",\"bis\":\"73779\"},{\"von\":\"74300\",\"bis\":\"74429\"},{\"von\":\"74500\",\"bis\":\"74549\"},{\"von\":\"75350\",\"bis\":\"75399\"},{\"von\":\"72300\",\"bis\":\"72369\"},{\"von\":\"72420\",\"bis\":\"72539\"},{\"von\":\"78000\",\"bis\":\"78089\"},{\"von\":\"78150\",\"bis\":\"78199\"},{\"von\":\"78200\",\"bis\":\"78269\"},{\"von\":\"78300\",\"bis\":\"78359\"},{\"von\":\"78400\",\"bis\":\"78479\"},{\"von\":\"78500\",\"bis\":\"78669\"},{\"von\":\"88000\",\"bis\":\"88099\"},{\"von\":\"88180\",\"bis\":\"88289\"},{\"von\":\"88320\",\"bis\":\"88529\"},{\"von\":\"88600\",\"bis\":\"88719\"},{\"von\":\"89000\",\"bis\":\"89199\"},{\"von\":\"89500\",\"bis\":\"89619\"},{\"von\":\"72150\",\"bis\":\"72299\"},{\"von\":\"75000\",\"bis\":\"75059\"},{\"von\":\"75100\",\"bis\":\"75249\"},{\"von\":\"75300\",\"bis\":\"75339\"},{\"von\":\"75400\",\"bis\":\"75449\"},{\"von\":\"76000\",\"bis\":\"76359\"},{\"von\":\"76400\",\"bis\":\"76599\"},{\"von\":\"76600\",\"bis\":\"76779\"},{\"von\":\"76800\",\"bis\":\"76899\"},{\"von\":\"77600\",\"bis\":\"77889\"},{\"von\":\"77900\",\"bis\":\"77979\"},{\"von\":\"78090\",\"bis\":\"78149\"},{\"von\":\"78700\",\"bis\":\"78739\"},{\"von\":\"79000\",\"bis\":\"79429\"},{\"von\":\"79500\",\"bis\":\"79879\"}]'>\n                            <span class=\"htitle\">Serviceberater<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur individuellen Vor-Ort-Beratung f\u00fcr alle Servicethemen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Rene St\u00f6be<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-West<br>\n                                                                                                73529 Schw\u00e4bisch Gm\u00fcnd                            <\/p>\n\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491757256816\">+491757256816<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:rene.stoebe@efaflex.com\">rene.stoebe@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"04620\",\"bis\":\"04639\"},{\"von\":\"04700\",\"bis\":\"04749\"},{\"von\":\"07300\",\"bis\":\"07429\"},{\"von\":\"07500\",\"bis\":\"07589\"},{\"von\":\"07600\",\"bis\":\"07649\"},{\"von\":\"07700\",\"bis\":\"07779\"},{\"von\":\"07800\",\"bis\":\"07819\"},{\"von\":\"07900\",\"bis\":\"07989\"},{\"von\":\"08000\",\"bis\":\"08069\"},{\"von\":\"08100\",\"bis\":\"08149\"},{\"von\":\"08200\",\"bis\":\"08549\"},{\"von\":\"08600\",\"bis\":\"08609\"},{\"von\":\"08620\",\"bis\":\"08649\"},{\"von\":\"09000\",\"bis\":\"09249\"},{\"von\":\"09300\",\"bis\":\"09669\"},{\"von\":\"04000\",\"bis\":\"04469\"},{\"von\":\"04500\",\"bis\":\"04619\"},{\"von\":\"04640\",\"bis\":\"04689\"},{\"von\":\"04750\",\"bis\":\"04779\"},{\"von\":\"04800\",\"bis\":\"04939\"},{\"von\":\"06000\",\"bis\":\"06139\"},{\"von\":\"06170\",\"bis\":\"06579\"},{\"von\":\"06600\",\"bis\":\"06929\"},{\"von\":\"36400\",\"bis\":\"36469\"},{\"von\":\"37300\",\"bis\":\"37359\"},{\"von\":\"96500\",\"bis\":\"96529\"},{\"von\":\"98500\",\"bis\":\"98749\"},{\"von\":\"99000\",\"bis\":\"99109\"},{\"von\":\"99180\",\"bis\":\"99199\"},{\"von\":\"99300\",\"bis\":\"99339\"},{\"von\":\"99400\",\"bis\":\"99449\"},{\"von\":\"99500\",\"bis\":\"99519\"},{\"von\":\"99600\",\"bis\":\"99639\"},{\"von\":\"99700\",\"bis\":\"99769\"},{\"von\":\"99800\",\"bis\":\"99899\"},{\"von\":\"99940\",\"bis\":\"99999\"}]'>\n                            <span class=\"htitle\">Serviceberater<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur individuellen Vor-Ort-Beratung f\u00fcr alle Servicethemen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Sebastian Wittig<br>\n                                                                                                    Kundendienstniederlassung Nord-Ost<br>\n                                                                                                04416 Markkleeberg                            <\/p>\n\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491703756850\">+491703756850<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:sebastian.wittig@efaflex.com\">sebastian.wittig@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"10000\",\"bis\":\"10999\"},{\"von\":\"12000\",\"bis\":\"12689\"},{\"von\":\"13000\",\"bis\":\"13629\"},{\"von\":\"14000\",\"bis\":\"14199\"},{\"von\":\"14400\",\"bis\":\"14559\"},{\"von\":\"14600\",\"bis\":\"14669\"},{\"von\":\"14700\",\"bis\":\"14799\"},{\"von\":\"14800\",\"bis\":\"14829\"},{\"von\":\"14900\",\"bis\":\"14929\"},{\"von\":\"14930\",\"bis\":\"14979\"},{\"von\":\"15200\",\"bis\":\"15379\"},{\"von\":\"15500\",\"bis\":\"15569\"},{\"von\":\"15700\",\"bis\":\"15759\"},{\"von\":\"15800\",\"bis\":\"15899\"},{\"von\":\"15900\",\"bis\":\"15939\"},{\"von\":\"16200\",\"bis\":\"16359\"},{\"von\":\"16500\",\"bis\":\"16569\"},{\"von\":\"16720\",\"bis\":\"16869\"},{\"von\":\"16900\",\"bis\":\"16949\"},{\"von\":\"17000\",\"bis\":\"17509\"},{\"von\":\"18000\",\"bis\":\"18379\"},{\"von\":\"18400\",\"bis\":\"18469\"},{\"von\":\"18500\",\"bis\":\"18609\"}]'>\n                            <span class=\"htitle\">Serviceberater<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur individuellen Vor-Ort-Beratung f\u00fcr alle Servicethemen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Sebastian Ritrich<br>\n                                                                                                    Kundendienstniederlassung Nord-Ost<br>\n                                                                                                15366  Neuenhagen b. Berlin                            <\/p>\n\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491703756849\">+491703756849<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:sebastian.ritrich@efaflex.com\">sebastian.ritrich@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"42000\",\"bis\":\"42499\"},{\"von\":\"42600\",\"bis\":\"42929\"},{\"von\":\"44000\",\"bis\":\"44389\"},{\"von\":\"44500\",\"bis\":\"44589\"},{\"von\":\"44600\",\"bis\":\"44659\"},{\"von\":\"44700\",\"bis\":\"44899\"},{\"von\":\"45500\",\"bis\":\"45549\"},{\"von\":\"51000\",\"bis\":\"51149\"},{\"von\":\"51300\",\"bis\":\"51519\"},{\"von\":\"51600\",\"bis\":\"51709\"},{\"von\":\"51750\",\"bis\":\"51789\"},{\"von\":\"57400\",\"bis\":\"57439\"},{\"von\":\"58000\",\"bis\":\"58339\"},{\"von\":\"58400\",\"bis\":\"58849\"},{\"von\":\"59000\",\"bis\":\"59229\"},{\"von\":\"59400\",\"bis\":\"59469\"},{\"von\":\"59700\",\"bis\":\"59889\"},{\"von\":\"59900\",\"bis\":\"59969\"}]'>\n                            <span class=\"htitle\">Serviceberater<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur individuellen Vor-Ort-Beratung f\u00fcr alle Servicethemen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Sebastian Gilles<br>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                40721  Hilden                            <\/p>\n\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491703756889\">+491703756889<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:sebastian.gilles@efaflex.com\">sebastian.gilles@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"40721\",\"bis\":\"40721\"},{\"von\":\"40789\",\"bis\":\"40789\"},{\"von\":\"40882\",\"bis\":\"40882\"},{\"von\":\"41468\",\"bis\":\"41468\"},{\"von\":\"41538\",\"bis\":\"41538\"},{\"von\":\"41540\",\"bis\":\"41540\"},{\"von\":\"42113\",\"bis\":\"42113\"},{\"von\":\"42117\",\"bis\":\"42117\"},{\"von\":\"47829\",\"bis\":\"47829\"},{\"von\":\"50226\",\"bis\":\"50225\"},{\"von\":\"50585\",\"bis\":\"50585\"},{\"von\":\"50676\",\"bis\":\"50676\"},{\"von\":\"50739\",\"bis\":\"50739\"},{\"von\":\"51063\",\"bis\":\"51063\"},{\"von\":\"51149\",\"bis\":\"51149\"},{\"von\":\"51368\",\"bis\":\"51368\"},{\"von\":\"51369\",\"bis\":\"51369\"},{\"von\":\"51373\",\"bis\":\"51373\"},{\"von\":\"51377\",\"bis\":\"51377\"},{\"von\":\"53909\",\"bis\":\"53909\"},{\"von\":\"59192\",\"bis\":\"59192\"}]'>\n                            <span class=\"htitle\">Serviceberater<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur individuellen Vor-Ort-Beratung f\u00fcr alle Servicethemen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Martin Greinke<br>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                40721  Hilden                            <\/p>\n\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+4915116226363\">+4915116226363<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:martin.greinke@efaflex.com\">martin.greinke@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"91000\",\"bis\":\"91099\"},{\"von\":\"91250\",\"bis\":\"91369\"},{\"von\":\"95000\",\"bis\":\"95239\"},{\"von\":\"95300\",\"bis\":\"95369\"},{\"von\":\"95400\",\"bis\":\"95519\"},{\"von\":\"95600\",\"bis\":\"95709\"},{\"von\":\"96000\",\"bis\":\"96279\"},{\"von\":\"96300\",\"bis\":\"96369\"},{\"von\":\"96400\",\"bis\":\"96489\"},{\"von\":\"97000\",\"bis\":\"97359\"},{\"von\":\"97400\",\"bis\":\"97539\"},{\"von\":\"97600\",\"bis\":\"97859\"},{\"von\":\"73470\",\"bis\":\"73499\"},{\"von\":\"74000\",\"bis\":\"74259\"},{\"von\":\"74550\",\"bis\":\"74679\"},{\"von\":\"74700\",\"bis\":\"74749\"},{\"von\":\"90000\",\"bis\":\"90619\"},{\"von\":\"90700\",\"bis\":\"90769\"},{\"von\":\"91100\",\"bis\":\"91249\"},{\"von\":\"91400\",\"bis\":\"91489\"},{\"von\":\"91500\",\"bis\":\"91639\"},{\"von\":\"91700\",\"bis\":\"91809\"},{\"von\":\"92200\",\"bis\":\"92289\"},{\"von\":\"92300\",\"bis\":\"92369\"},{\"von\":\"92400\",\"bis\":\"92449\"},{\"von\":\"92500\",\"bis\":\"92559\"},{\"von\":\"92600\",\"bis\":\"92729\"},{\"von\":\"97860\",\"bis\":\"97999\"}]'>\n                            <span class=\"htitle\">Serviceberater<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur individuellen Vor-Ort-Beratung f\u00fcr alle Servicethemen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Joachim Stellmacher<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491703702466\">+491703702466<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:joachim.stellmacher@efaflex.com\">joachim.stellmacher@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"01000\",\"bis\":\"01329\"},{\"von\":\"01430\",\"bis\":\"01479\"},{\"von\":\"01550\",\"bis\":\"01859\"},{\"von\":\"01870\",\"bis\":\"01916\"},{\"von\":\"01916\",\"bis\":\"01999\"},{\"von\":\"02600\",\"bis\":\"02999\"},{\"von\":\"03000\",\"bis\":\"03259\"}]'>\n                            <span class=\"htitle\">Serviceberater<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur individuellen Vor-Ort-Beratung f\u00fcr alle Servicethemen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Sebastian Ritrich<br>\n                                                                                                    Kundendienstniederlassung Nord-Ost<br>\n                                                                                                04416 Markkleeberg                            <\/p>\n\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491703756849\">+491703756849<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:sebastian.ritrich@efaflex.com\">sebastian.ritrich@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"51530\",\"bis\":\"51599\"},{\"von\":\"53000\",\"bis\":\"53359\"},{\"von\":\"53400\",\"bis\":\"53509\"},{\"von\":\"53510\",\"bis\":\"53539\"},{\"von\":\"53540\",\"bis\":\"53639\"},{\"von\":\"53700\",\"bis\":\"53859\"},{\"von\":\"53860\",\"bis\":\"53949\"},{\"von\":\"57000\",\"bis\":\"57399\"},{\"von\":\"57440\",\"bis\":\"57489\"},{\"von\":\"57500\",\"bis\":\"57589\"},{\"von\":\"57600\",\"bis\":\"57649\"},{\"von\":\"40000\",\"bis\":\"40789\"},{\"von\":\"40800\",\"bis\":\"40889\"},{\"von\":\"41000\",\"bis\":\"41379\"},{\"von\":\"41400\",\"bis\":\"41569\"},{\"von\":\"41700\",\"bis\":\"41759\"},{\"von\":\"41800\",\"bis\":\"41849\"},{\"von\":\"42500\",\"bis\":\"42579\"},{\"von\":\"45950\",\"bis\":\"45969\"},{\"von\":\"50100\",\"bis\":\"50189\"},{\"von\":\"50200\",\"bis\":\"50259\"},{\"von\":\"50300\",\"bis\":\"50389\"},{\"von\":\"50440\",\"bis\":\"50999\"},{\"von\":\"52000\",\"bis\":\"52159\"},{\"von\":\"52200\",\"bis\":\"52249\"},{\"von\":\"52300\",\"bis\":\"52539\"},{\"von\":\"45000\",\"bis\":\"45359\"},{\"von\":\"45400\",\"bis\":\"45489\"},{\"von\":\"45600\",\"bis\":\"45779\"},{\"von\":\"45800\",\"bis\":\"45899\"},{\"von\":\"46000\",\"bis\":\"46149\"},{\"von\":\"46200\",\"bis\":\"46285\"},{\"von\":\"46420\",\"bis\":\"46569\"},{\"von\":\"47000\",\"bis\":\"47279\"},{\"von\":\"47400\",\"bis\":\"47669\"},{\"von\":\"47700\",\"bis\":\"47929\"}]'>\n                            <span class=\"htitle\">Serviceberater<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur individuellen Vor-Ort-Beratung f\u00fcr alle Servicethemen                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Roman Mannheims<br>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                40721 Hilden                            <\/p>\n\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491703702437\">+491703702437<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:roman.mannheims@efaflex.com\">roman.mannheims@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"70000\",\"bis\":\"70629\"},{\"von\":\"70700\",\"bis\":\"70839\"},{\"von\":\"71000\",\"bis\":\"71159\"},{\"von\":\"71200\",\"bis\":\"71409\"},{\"von\":\"71500\",\"bis\":\"71579\"},{\"von\":\"71600\",\"bis\":\"71739\"},{\"von\":\"72000\",\"bis\":\"72149\"},{\"von\":\"72370\",\"bis\":\"72419\"},{\"von\":\"72540\",\"bis\":\"72589\"},{\"von\":\"72600\",\"bis\":\"72669\"},{\"von\":\"72700\",\"bis\":\"72829\"},{\"von\":\"73000\",\"bis\":\"73119\"},{\"von\":\"73200\",\"bis\":\"73279\"},{\"von\":\"73300\",\"bis\":\"73349\"},{\"von\":\"73400\",\"bis\":\"73469\"},{\"von\":\"73500\",\"bis\":\"73579\"},{\"von\":\"73600\",\"bis\":\"73669\"},{\"von\":\"73700\",\"bis\":\"73779\"},{\"von\":\"74300\",\"bis\":\"74429\"},{\"von\":\"74500\",\"bis\":\"74549\"},{\"von\":\"75350\",\"bis\":\"75399\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Jonas Domin<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-West<br>\n                                                                                                73529 Schw\u00e4bisch Gm\u00fcnd                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+4971718741011\">+49717187410-11<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:jonas.domin@efaflex.com\">jonas.domin@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"82240\",\"bis\":\"82299\"},{\"von\":\"86000\",\"bis\":\"86579\"},{\"von\":\"86600\",\"bis\":\"86759\"},{\"von\":\"86800\",\"bis\":\"86949\"},{\"von\":\"86950\",\"bis\":\"86989\"},{\"von\":\"87400\",\"bis\":\"87789\"},{\"von\":\"88100\",\"bis\":\"88179\"},{\"von\":\"88290\",\"bis\":\"88319\"},{\"von\":\"89200\",\"bis\":\"89369\"},{\"von\":\"89400\",\"bis\":\"89449\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr B\u00e9la Schreiter<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582479\">+49876582-479<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:bela.schreiter@efaflex.com\">bela.schreiter@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"80001\",\"bis\":\"80999\"},{\"von\":\"81201\",\"bis\":\"81249\"},{\"von\":\"81301\",\"bis\":\"81379\"},{\"von\":\"81451\",\"bis\":\"81479\"},{\"von\":\"81501\",\"bis\":\"81549\"},{\"von\":\"81601\",\"bis\":\"81679\"},{\"von\":\"81701\",\"bis\":\"81739\"},{\"von\":\"81801\",\"bis\":\"81829\"},{\"von\":\"81901\",\"bis\":\"81929\"},{\"von\":\"82000\",\"bis\":\"82069\"},{\"von\":\"82100\",\"bis\":\"82239\"},{\"von\":\"82300\",\"bis\":\"82549\"},{\"von\":\"83000\",\"bis\":\"83139\"},{\"von\":\"83200\",\"bis\":\"83489\"},{\"von\":\"83500\",\"bis\":\"83569\"},{\"von\":\"83600\",\"bis\":\"83739\"},{\"von\":\"84400\",\"bis\":\"84579\"},{\"von\":\"85200\",\"bis\":\"85259\"},{\"von\":\"85500\",\"bis\":\"85669\"},{\"von\":\"85700\",\"bis\":\"85779\"},{\"von\":\"85045\",\"bis\":\"85045\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Frau Andrea Rieger<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582296\">+49876582-296<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:andrea.rieger@efaflex.com\">andrea.rieger@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"10000\",\"bis\":\"10999\"},{\"von\":\"12000\",\"bis\":\"12689\"},{\"von\":\"13000\",\"bis\":\"13689\"},{\"von\":\"14000\",\"bis\":\"14199\"},{\"von\":\"14400\",\"bis\":\"14559\"},{\"von\":\"14600\",\"bis\":\"14669\"},{\"von\":\"14700\",\"bis\":\"14799\"},{\"von\":\"14800\",\"bis\":\"14829\"},{\"von\":\"14900\",\"bis\":\"14929\"},{\"von\":\"14930\",\"bis\":\"14979\"},{\"von\":\"15200\",\"bis\":\"15379\"},{\"von\":\"15500\",\"bis\":\"15569\"},{\"von\":\"15700\",\"bis\":\"15759\"},{\"von\":\"15800\",\"bis\":\"15899\"},{\"von\":\"15900\",\"bis\":\"15939\"},{\"von\":\"16200\",\"bis\":\"16359\"},{\"von\":\"16500\",\"bis\":\"16569\"},{\"von\":\"16720\",\"bis\":\"16869\"},{\"von\":\"16900\",\"bis\":\"16949\"},{\"von\":\"17000\",\"bis\":\"17509\"},{\"von\":\"18000\",\"bis\":\"18379\"},{\"von\":\"18400\",\"bis\":\"18469\"},{\"von\":\"18500\",\"bis\":\"18609\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Frau Ilka Zanettel<br>\n                                                                                                    Kundendienstniederlassung Nord-Ost<br>\n                                                                                                15366 Neuenhagen b. Berlin                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+4933422134110\">+49334221341-10<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:ilka.zanettel@efaflex.com\">ilka.zanettel@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"51530\",\"bis\":\"51599\"},{\"von\":\"53000\",\"bis\":\"53359\"},{\"von\":\"53400\",\"bis\":\"53509\"},{\"von\":\"53510\",\"bis\":\"53539\"},{\"von\":\"53540\",\"bis\":\"53639\"},{\"von\":\"53700\",\"bis\":\"53859\"},{\"von\":\"53860\",\"bis\":\"53949\"},{\"von\":\"57000\",\"bis\":\"57399\"},{\"von\":\"57440\",\"bis\":\"57489\"},{\"von\":\"57500\",\"bis\":\"57589\"},{\"von\":\"57600\",\"bis\":\"57649\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Markus Klespe<br>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                40721 Hilden                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+492103509314\">+4921035093-14<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:markus.klespe@efaflex.com\">markus.klespe@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"35200\",\"bis\":\"35239\"},{\"von\":\"35660\",\"bis\":\"35799\"},{\"von\":\"54500\",\"bis\":\"54689\"},{\"von\":\"56000\",\"bis\":\"56379\"},{\"von\":\"56400\",\"bis\":\"56479\"},{\"von\":\"56500\",\"bis\":\"56659\"},{\"von\":\"56700\",\"bis\":\"56769\"},{\"von\":\"56800\",\"bis\":\"56869\"},{\"von\":\"65530\",\"bis\":\"65629\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Nikolas Koban<br>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                65479 Raunheim                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+496142991827\">+4961429918-27<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:nikolas.koban@efaflex.com\">nikolas.koban@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"45000\",\"bis\":\"45359\"},{\"von\":\"45400\",\"bis\":\"45489\"},{\"von\":\"45600\",\"bis\":\"45779\"},{\"von\":\"45800\",\"bis\":\"45899\"},{\"von\":\"46000\",\"bis\":\"46149\"},{\"von\":\"46200\",\"bis\":\"46285\"},{\"von\":\"46420\",\"bis\":\"46569\"},{\"von\":\"47000\",\"bis\":\"47279\"},{\"von\":\"47400\",\"bis\":\"47669\"},{\"von\":\"47700\",\"bis\":\"47929\"},{\"von\":\"42000\",\"bis\":\"42499\"},{\"von\":\"42600\",\"bis\":\"42929\"},{\"von\":\"44000\",\"bis\":\"44389\"},{\"von\":\"44500\",\"bis\":\"44589\"},{\"von\":\"44600\",\"bis\":\"44659\"},{\"von\":\"44700\",\"bis\":\"44899\"},{\"von\":\"45500\",\"bis\":\"45549\"},{\"von\":\"51000\",\"bis\":\"51149\"},{\"von\":\"51300\",\"bis\":\"51519\"},{\"von\":\"51600\",\"bis\":\"51709\"},{\"von\":\"51750\",\"bis\":\"51789\"},{\"von\":\"57400\",\"bis\":\"57439\"},{\"von\":\"58000\",\"bis\":\"58339\"},{\"von\":\"58400\",\"bis\":\"58849\"},{\"von\":\"59000\",\"bis\":\"59229\"},{\"von\":\"59400\",\"bis\":\"59469\"},{\"von\":\"59700\",\"bis\":\"59889\"},{\"von\":\"59900\",\"bis\":\"59969\"},{\"von\":\"42000\",\"bis\":\"42499\"},{\"von\":\"42600\",\"bis\":\"42929\"},{\"von\":\"44000\",\"bis\":\"44389\"},{\"von\":\"44500\",\"bis\":\"44589\"},{\"von\":\"44600\",\"bis\":\"44659\"},{\"von\":\"44700\",\"bis\":\"44899\"},{\"von\":\"45500\",\"bis\":\"45549\"},{\"von\":\"51000\",\"bis\":\"51149\"},{\"von\":\"51300\",\"bis\":\"51519\"},{\"von\":\"51600\",\"bis\":\"51709\"},{\"von\":\"51750\",\"bis\":\"51789\"},{\"von\":\"57400\",\"bis\":\"57439\"},{\"von\":\"58000\",\"bis\":\"58339\"},{\"von\":\"58400\",\"bis\":\"58849\"},{\"von\":\"59000\",\"bis\":\"59229\"},{\"von\":\"59400\",\"bis\":\"59469\"},{\"von\":\"59700\",\"bis\":\"59889\"},{\"von\":\"59900\",\"bis\":\"59969\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Holger Bartmu\u00df<br>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                40721 Hilden                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49210350930\">+4921035093-0<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:holger.bartmuss@efaflex.com\">holger.bartmuss@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"34400\",\"bis\":\"34439\"},{\"von\":\"34440\",\"bis\":\"34519\"},{\"von\":\"34520\",\"bis\":\"34639\"},{\"von\":\"35000\",\"bis\":\"35119\"},{\"von\":\"35240\",\"bis\":\"35289\"},{\"von\":\"35300\",\"bis\":\"35469\"},{\"von\":\"35500\",\"bis\":\"35649\"},{\"von\":\"36000\",\"bis\":\"36399\"},{\"von\":\"37200\",\"bis\":\"37299\"},{\"von\":\"60000\",\"bis\":\"60599\"},{\"von\":\"61100\",\"bis\":\"61389\"},{\"von\":\"61400\",\"bis\":\"61479\"},{\"von\":\"63000\",\"bis\":\"63075\"},{\"von\":\"63151\",\"bis\":\"63179\"},{\"von\":\"63400\",\"bis\":\"63549\"},{\"von\":\"63550\",\"bis\":\"63599\"},{\"von\":\"63600\",\"bis\":\"63639\"},{\"von\":\"63640\",\"bis\":\"63699\"},{\"von\":\"63700\",\"bis\":\"63776\"},{\"von\":\"63802\",\"bis\":\"63831\"},{\"von\":\"65392\",\"bis\":\"65451\"},{\"von\":\"65500\",\"bis\":\"65529\"},{\"von\":\"65700\",\"bis\":\"65939\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Alexander Huber<br>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                65479 Raunheim                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+496142991824\">+4961429918-24<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:alexander.huber@efaflex.com\">alexander.huber@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"72300\",\"bis\":\"72369\"},{\"von\":\"72420\",\"bis\":\"72539\"},{\"von\":\"78000\",\"bis\":\"78089\"},{\"von\":\"78150\",\"bis\":\"78199\"},{\"von\":\"78200\",\"bis\":\"78269\"},{\"von\":\"78300\",\"bis\":\"78359\"},{\"von\":\"78400\",\"bis\":\"78479\"},{\"von\":\"78500\",\"bis\":\"78669\"},{\"von\":\"88000\",\"bis\":\"88099\"},{\"von\":\"88180\",\"bis\":\"88289\"},{\"von\":\"88320\",\"bis\":\"88529\"},{\"von\":\"88600\",\"bis\":\"88719\"},{\"von\":\"89000\",\"bis\":\"89199\"},{\"von\":\"89500\",\"bis\":\"89619\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Luigi Iannelli<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-West<br>\n                                                                                                73529 Schw\u00e4bisch Gm\u00fcnd                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+4971718741016\">+49717187410-16<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:luigi.iannelli@efaflex.com\">luigi.iannelli@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"04000\",\"bis\":\"04469\"},{\"von\":\"04500\",\"bis\":\"04619\"},{\"von\":\"04640\",\"bis\":\"04689\"},{\"von\":\"04750\",\"bis\":\"04779\"},{\"von\":\"04800\",\"bis\":\"04939\"},{\"von\":\"06000\",\"bis\":\"06139\"},{\"von\":\"06170\",\"bis\":\"06579\"},{\"von\":\"06600\",\"bis\":\"06929\"},{\"von\":\"36400\",\"bis\":\"36469\"},{\"von\":\"37300\",\"bis\":\"37359\"},{\"von\":\"96500\",\"bis\":\"96529\"},{\"von\":\"98500\",\"bis\":\"98749\"},{\"von\":\"99000\",\"bis\":\"99109\"},{\"von\":\"99180\",\"bis\":\"99199\"},{\"von\":\"99300\",\"bis\":\"99339\"},{\"von\":\"99400\",\"bis\":\"99449\"},{\"von\":\"99500\",\"bis\":\"99519\"},{\"von\":\"99600\",\"bis\":\"99639\"},{\"von\":\"99700\",\"bis\":\"99769\"},{\"von\":\"99800\",\"bis\":\"99899\"},{\"von\":\"99940\",\"bis\":\"99999\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Holger Winkler<br>\n                                                                                                    Kundendienstniederlassung Nord-Ost<br>\n                                                                                                04416 Markkleeberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+4934297987718\">+49342979877-18<\/a><\/span>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491602755420\">+491602755420<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:holger.winkler@efaflex.com\">holger.winkler@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"54200\",\"bis\":\"54349\"},{\"von\":\"54400\",\"bis\":\"54499\"},{\"von\":\"55380\",\"bis\":\"55629\"},{\"von\":\"55700\",\"bis\":\"55779\"},{\"von\":\"66000\",\"bis\":\"66999\"},{\"von\":\"67000\",\"bis\":\"67169\"},{\"von\":\"67200\",\"bis\":\"67379\"},{\"von\":\"67400\",\"bis\":\"67489\"},{\"von\":\"67600\",\"bis\":\"67759\"},{\"von\":\"67800\",\"bis\":\"67829\"},{\"von\":\"68000\",\"bis\":\"68549\"},{\"von\":\"68700\",\"bis\":\"68809\"},{\"von\":\"69000\",\"bis\":\"69259\"},{\"von\":\"69400\",\"bis\":\"69519\"},{\"von\":\"74800\",\"bis\":\"74939\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Kai Ruthard<br>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                65479 Raunheim                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+496142991815\">+4961429918-15<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:kai.ruthard@efaflex.com\">kai.ruthard@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"40000\",\"bis\":\"40789\"},{\"von\":\"40800\",\"bis\":\"40889\"},{\"von\":\"41000\",\"bis\":\"41379\"},{\"von\":\"41400\",\"bis\":\"41569\"},{\"von\":\"41700\",\"bis\":\"41759\"},{\"von\":\"41800\",\"bis\":\"41849\"},{\"von\":\"42500\",\"bis\":\"42579\"},{\"von\":\"45950\",\"bis\":\"45969\"},{\"von\":\"50100\",\"bis\":\"50189\"},{\"von\":\"50200\",\"bis\":\"50259\"},{\"von\":\"50300\",\"bis\":\"50389\"},{\"von\":\"50440\",\"bis\":\"50999\"},{\"von\":\"52000\",\"bis\":\"52159\"},{\"von\":\"52200\",\"bis\":\"52249\"},{\"von\":\"52300\",\"bis\":\"52539\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Benjamin Franz<br>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                40721 Hilden                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+492103509318\">+4921035093-18<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:benjamin.franz@efaflex.com\">benjamin.franz@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"55000\",\"bis\":\"55299\"},{\"von\":\"63076\",\"bis\":\"63150\"},{\"von\":\"63200\",\"bis\":\"63329\"},{\"von\":\"63777\",\"bis\":\"63801\"},{\"von\":\"63832\",\"bis\":\"63939\"},{\"von\":\"64200\",\"bis\":\"64409\"},{\"von\":\"64500\",\"bis\":\"64589\"},{\"von\":\"64600\",\"bis\":\"64689\"},{\"von\":\"64700\",\"bis\":\"64759\"},{\"von\":\"64800\",\"bis\":\"64859\"},{\"von\":\"65000\",\"bis\":\"65239\"},{\"von\":\"65300\",\"bis\":\"65391\"},{\"von\":\"65452\",\"bis\":\"65479\"},{\"von\":\"67500\",\"bis\":\"67599\"},{\"von\":\"68600\",\"bis\":\"68649\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Marius Renner<br>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                65479  Raunheim                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+496142991828\">+4961429918-28<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:marius.renner@efaflex.com\">marius.renner@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"72300\",\"bis\":\"72369\"},{\"von\":\"72420\",\"bis\":\"72539\"},{\"von\":\"78000\",\"bis\":\"78089\"},{\"von\":\"78150\",\"bis\":\"78199\"},{\"von\":\"78200\",\"bis\":\"78269\"},{\"von\":\"78300\",\"bis\":\"78359\"},{\"von\":\"78400\",\"bis\":\"78479\"},{\"von\":\"78500\",\"bis\":\"78669\"},{\"von\":\"88000\",\"bis\":\"88099\"},{\"von\":\"88180\",\"bis\":\"88289\"},{\"von\":\"88320\",\"bis\":\"88529\"},{\"von\":\"88600\",\"bis\":\"88719\"},{\"von\":\"89000\",\"bis\":\"89199\"},{\"von\":\"89500\",\"bis\":\"89619\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Luigi Ianelli<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-West<br>\n                                                                                                73529  Schw\u00e4bisch Gm\u00fcnd                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+4971718741016\">+49717187410-16<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:luigi.iannelli@efaflex.com\">luigi.iannelli@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"72150\",\"bis\":\"72299\"},{\"von\":\"75000\",\"bis\":\"75059\"},{\"von\":\"75100\",\"bis\":\"75249\"},{\"von\":\"75300\",\"bis\":\"75339\"},{\"von\":\"75400\",\"bis\":\"75449\"},{\"von\":\"76000\",\"bis\":\"76359\"},{\"von\":\"76400\",\"bis\":\"76599\"},{\"von\":\"76600\",\"bis\":\"76779\"},{\"von\":\"76800\",\"bis\":\"76899\"},{\"von\":\"77600\",\"bis\":\"77889\"},{\"von\":\"77900\",\"bis\":\"77979\"},{\"von\":\"78090\",\"bis\":\"78149\"},{\"von\":\"78700\",\"bis\":\"78739\"},{\"von\":\"79000\",\"bis\":\"79429\"},{\"von\":\"79500\",\"bis\":\"79879\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Sven Antonucci<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-West<br>\n                                                                                                73529 Schw\u00e4bisch Gm\u00fcnd                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+4971718741022\">+49 7171 87410-22<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:sven.antonucci@efaflex.com\">sven.antonucci@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"40721\",\"bis\":\"40721\"},{\"von\":\"40789\",\"bis\":\"40789\"},{\"von\":\"40882\",\"bis\":\"40882\"},{\"von\":\"41468\",\"bis\":\"41468\"},{\"von\":\"41538\",\"bis\":\"41538\"},{\"von\":\"41540\",\"bis\":\"41540\"},{\"von\":\"42113\",\"bis\":\"42113\"},{\"von\":\"42117\",\"bis\":\"42117\"},{\"von\":\"47829\",\"bis\":\"47829\"},{\"von\":\"50226\",\"bis\":\"50226\"},{\"von\":\"50585\",\"bis\":\"50585\"},{\"von\":\"50676\",\"bis\":\"50676\"},{\"von\":\"50739\",\"bis\":\"50739\"},{\"von\":\"51063\",\"bis\":\"51063\"},{\"von\":\"51149\",\"bis\":\"51149\"},{\"von\":\"51368\",\"bis\":\"51368\"},{\"von\":\"51369\",\"bis\":\"51369\"},{\"von\":\"51373\",\"bis\":\"51373\"},{\"von\":\"51377\",\"bis\":\"51377\"},{\"von\":\"53909\",\"bis\":\"53909\"},{\"von\":\"59192\",\"bis\":\"59192\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Daniel Ochudlo<br>\n                                                                                                    Kundendienstniederlassung West<br>\n                                                                                                40721 Hilden                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+492103509313\">+4921035093-13<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:daniel.ochudlo@efaflex.com\">daniel.ochudlo@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"91000\",\"bis\":\"91099\"},{\"von\":\"91250\",\"bis\":\"91369\"},{\"von\":\"95000\",\"bis\":\"95239\"},{\"von\":\"95300\",\"bis\":\"95369\"},{\"von\":\"95400\",\"bis\":\"95519\"},{\"von\":\"95600\",\"bis\":\"95709\"},{\"von\":\"96000\",\"bis\":\"96279\"},{\"von\":\"96300\",\"bis\":\"96369\"},{\"von\":\"96400\",\"bis\":\"96489\"},{\"von\":\"97000\",\"bis\":\"97359\"},{\"von\":\"97400\",\"bis\":\"97539\"},{\"von\":\"97600\",\"bis\":\"97859\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Alexander Rank<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582189\">+49876582-189<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:alexander.rank@efaflex.com\">alexander.rank@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"73470\",\"bis\":\"73499\"},{\"von\":\"74000\",\"bis\":\"74259\"},{\"von\":\"74550\",\"bis\":\"74679\"},{\"von\":\"74700\",\"bis\":\"74749\"},{\"von\":\"90000\",\"bis\":\"90619\"},{\"von\":\"90700\",\"bis\":\"90769\"},{\"von\":\"91100\",\"bis\":\"91249\"},{\"von\":\"91400\",\"bis\":\"91489\"},{\"von\":\"91500\",\"bis\":\"91639\"},{\"von\":\"91700\",\"bis\":\"91809\"},{\"von\":\"92200\",\"bis\":\"92289\"},{\"von\":\"92300\",\"bis\":\"92369\"},{\"von\":\"92400\",\"bis\":\"92449\"},{\"von\":\"92500\",\"bis\":\"92559\"},{\"von\":\"92600\",\"bis\":\"92729\"},{\"von\":\"97860\",\"bis\":\"97999\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Tobias Obermaier<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582368\">+49876582-368<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:tobias.obermaier@efaflex.com\">tobias.obermaier@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"80001\",\"bis\":\"80999\"},{\"von\":\"81201\",\"bis\":\"81249\"},{\"von\":\"81301\",\"bis\":\"81379\"},{\"von\":\"81451\",\"bis\":\"81479\"},{\"von\":\"81501\",\"bis\":\"81549\"},{\"von\":\"81601\",\"bis\":\"81679\"},{\"von\":\"81701\",\"bis\":\"81739\"},{\"von\":\"81801\",\"bis\":\"81829\"},{\"von\":\"81901\",\"bis\":\"81929\"},{\"von\":\"82000\",\"bis\":\"82069\"},{\"von\":\"82100\",\"bis\":\"82239\"},{\"von\":\"82300\",\"bis\":\"82549\"},{\"von\":\"83000\",\"bis\":\"83139\"},{\"von\":\"83200\",\"bis\":\"83489\"},{\"von\":\"83500\",\"bis\":\"83569\"},{\"von\":\"83600\",\"bis\":\"83739\"},{\"von\":\"84400\",\"bis\":\"84579\"},{\"von\":\"85200\",\"bis\":\"85259\"},{\"von\":\"85500\",\"bis\":\"85669\"},{\"von\":\"85700\",\"bis\":\"85779\"},{\"von\":\"85045\",\"bis\":\"85045\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Frau Jessica Eibl<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582412\">+49876582-412<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:jessica.eibl@efaflex.com\">jessica.eibl@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"73470\",\"bis\":\"73499\"},{\"von\":\"74000\",\"bis\":\"74259\"},{\"von\":\"74550\",\"bis\":\"74679\"},{\"von\":\"74700\",\"bis\":\"74749\"},{\"von\":\"90000\",\"bis\":\"90619\"},{\"von\":\"90700\",\"bis\":\"90769\"},{\"von\":\"91100\",\"bis\":\"91249\"},{\"von\":\"91400\",\"bis\":\"91489\"},{\"von\":\"91500\",\"bis\":\"91639\"},{\"von\":\"91700\",\"bis\":\"91809\"},{\"von\":\"92200\",\"bis\":\"92289\"},{\"von\":\"92300\",\"bis\":\"92369\"},{\"von\":\"92400\",\"bis\":\"92449\"},{\"von\":\"92500\",\"bis\":\"92559\"},{\"von\":\"92600\",\"bis\":\"92729\"},{\"von\":\"97860\",\"bis\":\"97999\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Frau Kerstin Bauer<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582343\">+49876582343<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:kerstin.bauer@efaflex.com\">kerstin.bauer@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"01000\",\"bis\":\"01329\"},{\"von\":\"01430\",\"bis\":\"01479\"},{\"von\":\"01550\",\"bis\":\"01859\"},{\"von\":\"01870\",\"bis\":\"01999\"},{\"von\":\"02600\",\"bis\":\"02999\"},{\"von\":\"03000\",\"bis\":\"03259\"},{\"von\":\"04620\",\"bis\":\"04639\"},{\"von\":\"04700\",\"bis\":\"04749\"},{\"von\":\"07300\",\"bis\":\"07429\"},{\"von\":\"07500\",\"bis\":\"07589\"},{\"von\":\"07600\",\"bis\":\"07649\"},{\"von\":\"07700\",\"bis\":\"07779\"},{\"von\":\"07800\",\"bis\":\"07819\"},{\"von\":\"07900\",\"bis\":\"07989\"},{\"von\":\"08000\",\"bis\":\"08069\"},{\"von\":\"08100\",\"bis\":\"08149\"},{\"von\":\"08200\",\"bis\":\"08549\"},{\"von\":\"08600\",\"bis\":\"08609\"},{\"von\":\"08620\",\"bis\":\"08649\"},{\"von\":\"09000\",\"bis\":\"09249\"},{\"von\":\"09300\",\"bis\":\"09669\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Dennis Eichholz<br>\n                                                                                                    Kundendienstniederlassung Nord-Ost<br>\n                                                                                                04416 Markkleeberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+4934297987716\">+49342979877-16<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:dennis.eichholz@efaflex.com\">dennis.eichholz@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"84000\",\"bis\":\"84109\"},{\"von\":\"84120\",\"bis\":\"84189\"},{\"von\":\"84300\",\"bis\":\"84389\"},{\"von\":\"85000\",\"bis\":\"85044\"},{\"von\":\"85046\",\"bis\":\"85139\"},{\"von\":\"85260\",\"bis\":\"85469\"},{\"von\":\"93000\",\"bis\":\"93109\"},{\"von\":\"93120\",\"bis\":\"93199\"},{\"von\":\"93300\",\"bis\":\"93359\"},{\"von\":\"93400\",\"bis\":\"93499\"},{\"von\":\"94000\",\"bis\":\"94169\"},{\"von\":\"94200\",\"bis\":\"94269\"},{\"von\":\"94300\",\"bis\":\"94379\"},{\"von\":\"94400\",\"bis\":\"94579\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Florian G\u00f6tzberger<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582532\">+49876582-532<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:florian.goetzberger@efaflex.com\">florian.goetzberger@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"84000\",\"bis\":\"84109\"},{\"von\":\"84120\",\"bis\":\"84189\"},{\"von\":\"84300\",\"bis\":\"84389\"},{\"von\":\"85000\",\"bis\":\"85044\"},{\"von\":\"85046\",\"bis\":\"85139\"},{\"von\":\"85260\",\"bis\":\"85469\"},{\"von\":\"93000\",\"bis\":\"93109\"},{\"von\":\"93120\",\"bis\":\"93199\"},{\"von\":\"93300\",\"bis\":\"93359\"},{\"von\":\"93400\",\"bis\":\"93499\"},{\"von\":\"94000\",\"bis\":\"94169\"},{\"von\":\"94200\",\"bis\":\"94269\"},{\"von\":\"94300\",\"bis\":\"94379\"},{\"von\":\"94400\",\"bis\":\"94579\"}]'>\n                            <span class=\"htitle\">Servicemanager<\/span>\n                                                            <p>\n                                    <strong>\n                                        Ihr Ansprechpartner zur Termin- und Materialdisposition                                    <\/strong>\n                                <\/p>\n                                                        <p>\n                                                                    Herr Christoph Lintsche<br>\n                                                                                                    Kundendienstniederlassung S\u00fcd-Ost<br>\n                                                                                                84079 Bruckberg                            <\/p>\n\n                                                            <p>\n                                                                    <span class=\"cb-icon cb-icon-phone\"><a href=\"tel:+49876582285\">+49876582285<\/a><\/span>\n                                                                                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:Christoph.Lintsche@efaflex.com\">Christoph.Lintsche@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n                                    <\/div>\n        <\/div>\n\n        <div class=\"inner\">\n            <div class=\"zweispaltig-bild-text-modul custom-flex-box\">\n                <h2 class=\"standhl\" style=\"display:none;\">Vertriebs- und Neutoranfragen<\/h2>\n            <\/div>\n        <\/div>\n\n        <div class=\"inner\">\n            <div class=\"standorte_plz custom-flex-box\">\n                                        <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"19000\",\"bis\":\"19089\"},{\"von\":\"19200\",\"bis\":\"19419\"},{\"von\":\"20000\",\"bis\":\"20539\"},{\"von\":\"21000\",\"bis\":\"21279\"},{\"von\":\"21300\",\"bis\":\"21529\"},{\"von\":\"21600\",\"bis\":\"21789\"},{\"von\":\"22000\",\"bis\":\"22889\"},{\"von\":\"22900\",\"bis\":\"22969\"},{\"von\":\"23500\",\"bis\":\"23629\"},{\"von\":\"23660\",\"bis\":\"24259\"},{\"von\":\"24300\",\"bis\":\"24409\"},{\"von\":\"24500\",\"bis\":\"24649\"},{\"von\":\"24750\",\"bis\":\"24999\"},{\"von\":\"25300\",\"bis\":\"25379\"},{\"von\":\"25400\",\"bis\":\"25599\"},{\"von\":\"25690\",\"bis\":\"25999\"},{\"von\":\"29430\",\"bis\":\"29649\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Dipl. Ing. R\u00fcdiger Gehrke<br>\n                                                                                                                                21357 Bardowick                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491716952391\">+491716952391<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:ruediger.gehrke@efaflex.com\">ruediger.gehrke@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"35200\",\"bis\":\"35239\"},{\"von\":\"35660\",\"bis\":\"35799\"},{\"von\":\"51530\",\"bis\":\"51599\"},{\"von\":\"53000\",\"bis\":\"53359\"},{\"von\":\"53400\",\"bis\":\"53509\"},{\"von\":\"53510\",\"bis\":\"53539\"},{\"von\":\"53540\",\"bis\":\"53639\"},{\"von\":\"53700\",\"bis\":\"53859\"},{\"von\":\"53860\",\"bis\":\"53949\"},{\"von\":\"54500\",\"bis\":\"54689\"},{\"von\":\"56000\",\"bis\":\"56379\"},{\"von\":\"56400\",\"bis\":\"56479\"},{\"von\":\"56500\",\"bis\":\"56659\"},{\"von\":\"56700\",\"bis\":\"56769\"},{\"von\":\"56800\",\"bis\":\"56869\"},{\"von\":\"57000\",\"bis\":\"57399\"},{\"von\":\"57440\",\"bis\":\"57489\"},{\"von\":\"57500\",\"bis\":\"57589\"},{\"von\":\"57600\",\"bis\":\"57649\"},{\"von\":\"65530\",\"bis\":\"65629\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Marcel Hehl<br>\n                                                                                                                                56410 Montabaur                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+4915119546337\">+4915119546337<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:marcel.hehl@efaflex.com\">marcel.hehl@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"84307\",\"bis\":\"84307\"},{\"von\":\"84326\",\"bis\":\"84389\"},{\"von\":\"93086\",\"bis\":\"93086\"},{\"von\":\"93090\",\"bis\":\"93090\"},{\"von\":\"93099\",\"bis\":\"93099\"},{\"von\":\"93102\",\"bis\":\"93104\"},{\"von\":\"93109\",\"bis\":\"93109\"},{\"von\":\"93167\",\"bis\":\"93167\"},{\"von\":\"93177\",\"bis\":\"93179\"},{\"von\":\"93185\",\"bis\":\"93185\"},{\"von\":\"93189\",\"bis\":\"93194\"},{\"von\":\"93199\",\"bis\":\"93199\"},{\"von\":\"93400\",\"bis\":\"94341\"},{\"von\":\"94343\",\"bis\":\"94579\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Igor Polovic<br>\n                                                                                                                                94469 Deggendorf                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491703756880\">+491703756880<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:igor.polovic@efaflex.com\">igor.polovic@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"80001\",\"bis\":\"80999\"},{\"von\":\"81201\",\"bis\":\"81249\"},{\"von\":\"81301\",\"bis\":\"81379\"},{\"von\":\"81451\",\"bis\":\"81479\"},{\"von\":\"81501\",\"bis\":\"81549\"},{\"von\":\"81601\",\"bis\":\"81679\"},{\"von\":\"81701\",\"bis\":\"81739\"},{\"von\":\"81801\",\"bis\":\"81829\"},{\"von\":\"81901\",\"bis\":\"81929\"},{\"von\":\"82000\",\"bis\":\"82069\"},{\"von\":\"82100\",\"bis\":\"82239\"},{\"von\":\"82300\",\"bis\":\"82549\"},{\"von\":\"83000\",\"bis\":\"83139\"},{\"von\":\"83200\",\"bis\":\"83489\"},{\"von\":\"83500\",\"bis\":\"83569\"},{\"von\":\"83600\",\"bis\":\"83739\"},{\"von\":\"84400\",\"bis\":\"84579\"},{\"von\":\"85200\",\"bis\":\"85259\"},{\"von\":\"85500\",\"bis\":\"85669\"},{\"von\":\"85700\",\"bis\":\"85779\"},{\"von\":\"85045\",\"bis\":\"85045\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Oliver Chadt<br>\n                                                                                                                                85435 Erding                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491707811175\">+491707811175<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:oliver.chadt@efaflex.com\">oliver.chadt@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"72150\",\"bis\":\"72299\"},{\"von\":\"75000\",\"bis\":\"75059\"},{\"von\":\"75100\",\"bis\":\"75249\"},{\"von\":\"75300\",\"bis\":\"75339\"},{\"von\":\"75400\",\"bis\":\"75449\"},{\"von\":\"76000\",\"bis\":\"76359\"},{\"von\":\"76400\",\"bis\":\"76599\"},{\"von\":\"76600\",\"bis\":\"76779\"},{\"von\":\"76800\",\"bis\":\"76899\"},{\"von\":\"77600\",\"bis\":\"77889\"},{\"von\":\"77900\",\"bis\":\"77979\"},{\"von\":\"78090\",\"bis\":\"78149\"},{\"von\":\"78700\",\"bis\":\"78739\"},{\"von\":\"79000\",\"bis\":\"79429\"},{\"von\":\"79500\",\"bis\":\"79879\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Dipl. Wirt. Ing. Christoph Jaspers<br>\n                                                                                                                                76534 Baden &#8211; Baden                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491714757069\">+491714757069<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:christoph.jaspers@efaflex.com\">christoph.jaspers@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"73470\",\"bis\":\"73499\"},{\"von\":\"74000\",\"bis\":\"74259\"},{\"von\":\"74550\",\"bis\":\"74679\"},{\"von\":\"74700\",\"bis\":\"74749\"},{\"von\":\"90000\",\"bis\":\"90619\"},{\"von\":\"90700\",\"bis\":\"90769\"},{\"von\":\"91100\",\"bis\":\"91249\"},{\"von\":\"91400\",\"bis\":\"91489\"},{\"von\":\"91500\",\"bis\":\"91639\"},{\"von\":\"91700\",\"bis\":\"91809\"},{\"von\":\"92200\",\"bis\":\"92289\"},{\"von\":\"92300\",\"bis\":\"92369\"},{\"von\":\"92400\",\"bis\":\"92449\"},{\"von\":\"92500\",\"bis\":\"92559\"},{\"von\":\"92600\",\"bis\":\"92729\"},{\"von\":\"97860\",\"bis\":\"97999\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Christoph Maul<br>\n                                                                                                                                90607 R\u00fcckersdorf                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491607038312\">+491607038312<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:christoph.maul@efaflex.com\">christoph.maul@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"82240\",\"bis\":\"82299\"},{\"von\":\"86000\",\"bis\":\"86579\"},{\"von\":\"86600\",\"bis\":\"86759\"},{\"von\":\"86800\",\"bis\":\"86949\"},{\"von\":\"86950\",\"bis\":\"86989\"},{\"von\":\"87400\",\"bis\":\"87789\"},{\"von\":\"88100\",\"bis\":\"88179\"},{\"von\":\"88290\",\"bis\":\"88319\"},{\"von\":\"89200\",\"bis\":\"89369\"},{\"von\":\"89400\",\"bis\":\"89449\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Reinhold Eckert<br>\n                                                                                                                                86574 Alsmoos                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491702223519\">+491702223519<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:reinhold.eckert@efaflex.com\">reinhold.eckert@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"70000\",\"bis\":\"70629\"},{\"von\":\"70700\",\"bis\":\"70839\"},{\"von\":\"71000\",\"bis\":\"71159\"},{\"von\":\"71200\",\"bis\":\"71409\"},{\"von\":\"71500\",\"bis\":\"71579\"},{\"von\":\"71600\",\"bis\":\"71739\"},{\"von\":\"72000\",\"bis\":\"72149\"},{\"von\":\"72370\",\"bis\":\"72419\"},{\"von\":\"72540\",\"bis\":\"72589\"},{\"von\":\"72600\",\"bis\":\"72669\"},{\"von\":\"72700\",\"bis\":\"72829\"},{\"von\":\"73000\",\"bis\":\"73119\"},{\"von\":\"73200\",\"bis\":\"73279\"},{\"von\":\"73300\",\"bis\":\"73349\"},{\"von\":\"73400\",\"bis\":\"73469\"},{\"von\":\"73500\",\"bis\":\"73579\"},{\"von\":\"73600\",\"bis\":\"73669\"},{\"von\":\"73700\",\"bis\":\"73779\"},{\"von\":\"74300\",\"bis\":\"74429\"},{\"von\":\"74500\",\"bis\":\"74549\"},{\"von\":\"75350\",\"bis\":\"75399\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Dietmar Schurr<br>\n                                                                                                                                73312 Geislingen \/ Steige                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491607038314\">+491607038314<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:dietmar.schurr@efaflex.com\">dietmar.schurr@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"01000\",\"bis\":\"01329\"},{\"von\":\"01430\",\"bis\":\"01479\"},{\"von\":\"01550\",\"bis\":\"01859\"},{\"von\":\"01870\",\"bis\":\"01999\"},{\"von\":\"02600\",\"bis\":\"02999\"},{\"von\":\"03000\",\"bis\":\"03259\"},{\"von\":\"04620\",\"bis\":\"04639\"},{\"von\":\"04700\",\"bis\":\"04749\"},{\"von\":\"07300\",\"bis\":\"07429\"},{\"von\":\"07500\",\"bis\":\"07589\"},{\"von\":\"07600\",\"bis\":\"07649\"},{\"von\":\"07700\",\"bis\":\"07779\"},{\"von\":\"07800\",\"bis\":\"07819\"},{\"von\":\"07900\",\"bis\":\"07989\"},{\"von\":\"08000\",\"bis\":\"08069\"},{\"von\":\"08100\",\"bis\":\"08149\"},{\"von\":\"08200\",\"bis\":\"08549\"},{\"von\":\"08600\",\"bis\":\"08609\"},{\"von\":\"08620\",\"bis\":\"08649\"},{\"von\":\"09000\",\"bis\":\"09249\"},{\"von\":\"09300\",\"bis\":\"09669\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Thomas Weile<br>\n                                                                                                                                01257 Dresden                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491718620569\">+491718620569<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:thomas.weile@efaflex.com\">thomas.weile@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"04000\",\"bis\":\"04469\"},{\"von\":\"04500\",\"bis\":\"04619\"},{\"von\":\"04640\",\"bis\":\"04689\"},{\"von\":\"04750\",\"bis\":\"04779\"},{\"von\":\"04800\",\"bis\":\"04939\"},{\"von\":\"06000\",\"bis\":\"06139\"},{\"von\":\"06170\",\"bis\":\"06579\"},{\"von\":\"06600\",\"bis\":\"06929\"},{\"von\":\"36400\",\"bis\":\"36469\"},{\"von\":\"37300\",\"bis\":\"37359\"},{\"von\":\"96500\",\"bis\":\"96529\"},{\"von\":\"98500\",\"bis\":\"98749\"},{\"von\":\"99000\",\"bis\":\"99109\"},{\"von\":\"99180\",\"bis\":\"99199\"},{\"von\":\"99300\",\"bis\":\"99339\"},{\"von\":\"99400\",\"bis\":\"99449\"},{\"von\":\"99500\",\"bis\":\"99519\"},{\"von\":\"99600\",\"bis\":\"99639\"},{\"von\":\"99700\",\"bis\":\"99769\"},{\"von\":\"99800\",\"bis\":\"99899\"},{\"von\":\"99940\",\"bis\":\"99999\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Falk Posse<br>\n                                                                                                                                99094 Erfurt                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491718620570\">+491718620570<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:falk.posse@efaflex.com\">falk.posse@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"40000\",\"bis\":\"40789\"},{\"von\":\"40800\",\"bis\":\"40889\"},{\"von\":\"41000\",\"bis\":\"41379\"},{\"von\":\"41400\",\"bis\":\"41569\"},{\"von\":\"41700\",\"bis\":\"41759\"},{\"von\":\"41800\",\"bis\":\"41849\"},{\"von\":\"42500\",\"bis\":\"42579\"},{\"von\":\"45000\",\"bis\":\"45359\"},{\"von\":\"45400\",\"bis\":\"45489\"},{\"von\":\"45600\",\"bis\":\"45779\"},{\"von\":\"45800\",\"bis\":\"45899\"},{\"von\":\"45950\",\"bis\":\"45969\"},{\"von\":\"46000\",\"bis\":\"46149\"},{\"von\":\"46200\",\"bis\":\"46289\"},{\"von\":\"46420\",\"bis\":\"46569\"},{\"von\":\"47000\",\"bis\":\"47279\"},{\"von\":\"47400\",\"bis\":\"47669\"},{\"von\":\"47700\",\"bis\":\"47929\"},{\"von\":\"50100\",\"bis\":\"50189\"},{\"von\":\"50200\",\"bis\":\"50259\"},{\"von\":\"50300\",\"bis\":\"50389\"},{\"von\":\"50440\",\"bis\":\"50999\"},{\"von\":\"52000\",\"bis\":\"52159\"},{\"von\":\"52200\",\"bis\":\"52249\"},{\"von\":\"52300\",\"bis\":\"52539\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Torsten Emde<br>\n                                                                                                                                42549 Velbert                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491757227924\">+491757227924<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:torsten.emde@efaflex.com\">torsten.emde@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"42000\",\"bis\":\"42499\"},{\"von\":\"42600\",\"bis\":\"42929\"},{\"von\":\"44000\",\"bis\":\"44389\"},{\"von\":\"44500\",\"bis\":\"44589\"},{\"von\":\"44598\",\"bis\":\"44659\"},{\"von\":\"44700\",\"bis\":\"44899\"},{\"von\":\"45501\",\"bis\":\"45549\"},{\"von\":\"51000\",\"bis\":\"51149\"},{\"von\":\"51300\",\"bis\":\"51519\"},{\"von\":\"57400\",\"bis\":\"57439\"},{\"von\":\"51600\",\"bis\":\"51709\"},{\"von\":\"51750\",\"bis\":\"51789\"},{\"von\":\"58000\",\"bis\":\"58339\"},{\"von\":\"58400\",\"bis\":\"58849\"},{\"von\":\"59000\",\"bis\":\"59229\"},{\"von\":\"59240\",\"bis\":\"59329\"},{\"von\":\"59400\",\"bis\":\"59469\"},{\"von\":\"59470\",\"bis\":\"59609\"},{\"von\":\"59700\",\"bis\":\"59889\"},{\"von\":\"59900\",\"bis\":\"59969\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Henning Krause<br>\n                                                                                                                                44791 Bochum                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491702234468\">+491702234468<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:henning.krause@efaflex.com\">henning.krause@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"54200\",\"bis\":\"54349\"},{\"von\":\"54400\",\"bis\":\"54499\"},{\"von\":\"55380\",\"bis\":\"55629\"},{\"von\":\"55700\",\"bis\":\"55779\"},{\"von\":\"66000\",\"bis\":\"66999\"},{\"von\":\"67000\",\"bis\":\"67169\"},{\"von\":\"67200\",\"bis\":\"67379\"},{\"von\":\"67400\",\"bis\":\"67489\"},{\"von\":\"67600\",\"bis\":\"67759\"},{\"von\":\"67800\",\"bis\":\"67829\"},{\"von\":\"68000\",\"bis\":\"68549\"},{\"von\":\"68700\",\"bis\":\"68809\"},{\"von\":\"69000\",\"bis\":\"69259\"},{\"von\":\"69400\",\"bis\":\"69519\"},{\"von\":\"74800\",\"bis\":\"74939\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Serdal Koccu<br>\n                                                                                                                                76726 Germersheim                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491703731801\">+491703731801<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:serdal.koccu@efaflex.com\">serdal.koccu@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"34520\",\"bis\":\"34639\"},{\"von\":\"35000\",\"bis\":\"35119\"},{\"von\":\"35250\",\"bis\":\"35289\"},{\"von\":\"35300\",\"bis\":\"35469\"},{\"von\":\"35500\",\"bis\":\"35649\"},{\"von\":\"36000\",\"bis\":\"36399\"},{\"von\":\"37200\",\"bis\":\"37299\"},{\"von\":\"55000\",\"bis\":\"55299\"},{\"von\":\"60000\",\"bis\":\"60599\"},{\"von\":\"61100\",\"bis\":\"61389\"},{\"von\":\"61400\",\"bis\":\"61479\"},{\"von\":\"63000\",\"bis\":\"63179\"},{\"von\":\"63200\",\"bis\":\"63329\"},{\"von\":\"63400\",\"bis\":\"63549\"},{\"von\":\"63550\",\"bis\":\"63599\"},{\"von\":\"63600\",\"bis\":\"63639\"},{\"von\":\"63640\",\"bis\":\"63699\"},{\"von\":\"63700\",\"bis\":\"63939\"},{\"von\":\"64200\",\"bis\":\"64409\"},{\"von\":\"64500\",\"bis\":\"64589\"},{\"von\":\"64600\",\"bis\":\"64689\"},{\"von\":\"64700\",\"bis\":\"64759\"},{\"von\":\"64800\",\"bis\":\"64859\"},{\"von\":\"65000\",\"bis\":\"65239\"},{\"von\":\"65300\",\"bis\":\"65479\"},{\"von\":\"65500\",\"bis\":\"65529\"},{\"von\":\"65700\",\"bis\":\"65939\"},{\"von\":\"67500\",\"bis\":\"67599\"},{\"von\":\"68600\",\"bis\":\"68649\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Dipl. Ing. Wolfgang Rauch<br>\n                                                                                                                                65474 Bischofsheim                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491716857715\">+491716857715<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:wolfgang.rauch@efaflex.com\">wolfgang.rauch@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"72300\",\"bis\":\"72369\"},{\"von\":\"72420\",\"bis\":\"72539\"},{\"von\":\"78000\",\"bis\":\"78089\"},{\"von\":\"78150\",\"bis\":\"78199\"},{\"von\":\"78200\",\"bis\":\"78269\"},{\"von\":\"78300\",\"bis\":\"78359\"},{\"von\":\"78400\",\"bis\":\"78479\"},{\"von\":\"78500\",\"bis\":\"78669\"},{\"von\":\"88000\",\"bis\":\"88099\"},{\"von\":\"88180\",\"bis\":\"88289\"},{\"von\":\"88320\",\"bis\":\"88529\"},{\"von\":\"88600\",\"bis\":\"88719\"},{\"von\":\"89000\",\"bis\":\"89199\"},{\"von\":\"89500\",\"bis\":\"89619\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Benjamin Laub<br>\n                                                                                                                                72810 Gomaringen                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491703702441\">+491703702441<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:benjamin.laub@efaflex.com\">benjamin.laub@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"29200\",\"bis\":\"29419\"},{\"von\":\"29650\",\"bis\":\"29699\"},{\"von\":\"31000\",\"bis\":\"31319\"},{\"von\":\"37000\",\"bis\":\"37199\"},{\"von\":\"37400\",\"bis\":\"37449\"},{\"von\":\"37500\",\"bis\":\"37589\"},{\"von\":\"38000\",\"bis\":\"38179\"},{\"von\":\"38200\",\"bis\":\"38389\"},{\"von\":\"38400\",\"bis\":\"38489\"},{\"von\":\"38500\",\"bis\":\"38559\"},{\"von\":\"38600\",\"bis\":\"38729\"},{\"von\":\"38800\",\"bis\":\"38899\"},{\"von\":\"39000\",\"bis\":\"39139\"},{\"von\":\"39150\",\"bis\":\"39179\"},{\"von\":\"39200\",\"bis\":\"39279\"},{\"von\":\"39280\",\"bis\":\"39399\"},{\"von\":\"39400\",\"bis\":\"39449\"},{\"von\":\"39510\",\"bis\":\"39539\"},{\"von\":\"39550\",\"bis\":\"39649\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Lars Barthel<br>\n                                                                                                                                39279 Leitzkau                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491752093170\">+491752093170<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:lars.barthel@efaflex.com\">lars.barthel@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"30000\",\"bis\":\"30989\"},{\"von\":\"31500\",\"bis\":\"31869\"},{\"von\":\"34000\",\"bis\":\"34399\"},{\"von\":\"34440\",\"bis\":\"34519\"},{\"von\":\"37590\",\"bis\":\"37649\"},{\"von\":\"32000\",\"bis\":\"32139\"},{\"von\":\"32210\",\"bis\":\"32289\"},{\"von\":\"32370\",\"bis\":\"32479\"},{\"von\":\"32500\",\"bis\":\"32609\"},{\"von\":\"32630\",\"bis\":\"32839\"},{\"von\":\"33000\",\"bis\":\"33039\"},{\"von\":\"33040\",\"bis\":\"33189\"},{\"von\":\"33240\",\"bis\":\"33449\"},{\"von\":\"33500\",\"bis\":\"33829\"},{\"von\":\"34400\",\"bis\":\"34439\"},{\"von\":\"37650\",\"bis\":\"37699\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Martin Beinlich<br>\n                                                                                                                                49124 Georgsmarienh\u00fctte                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491703757541\">+491703757541<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:martin.beinlich@efaflex.com\">martin.beinlich@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"91000\",\"bis\":\"91099\"},{\"von\":\"91250\",\"bis\":\"91369\"},{\"von\":\"95000\",\"bis\":\"95239\"},{\"von\":\"95300\",\"bis\":\"95369\"},{\"von\":\"95400\",\"bis\":\"95519\"},{\"von\":\"95600\",\"bis\":\"95709\"},{\"von\":\"96000\",\"bis\":\"96279\"},{\"von\":\"96300\",\"bis\":\"96369\"},{\"von\":\"96400\",\"bis\":\"96489\"},{\"von\":\"97000\",\"bis\":\"97359\"},{\"von\":\"97400\",\"bis\":\"97539\"},{\"von\":\"97600\",\"bis\":\"97859\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Marcel Martin<br>\n                                                                                                                                97631 Bad K\u00f6nigshofen                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+4916094475829\">+4916094475829<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:marcel.martin@efaflex.com\">marcel.martin@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"84000\",\"bis\":\"84189\"},{\"von\":\"84323\",\"bis\":\"84323\"},{\"von\":\"85000\",\"bis\":\"85044\"},{\"von\":\"85046\",\"bis\":\"85139\"},{\"von\":\"85260\",\"bis\":\"85469\"},{\"von\":\"93000\",\"bis\":\"93083\"},{\"von\":\"93087\",\"bis\":\"93089\"},{\"von\":\"93092\",\"bis\":\"93098\"},{\"von\":\"93101\",\"bis\":\"93101\"},{\"von\":\"93105\",\"bis\":\"93107\"},{\"von\":\"93120\",\"bis\":\"93164\"},{\"von\":\"93170\",\"bis\":\"93176\"},{\"von\":\"93180\",\"bis\":\"93183\"},{\"von\":\"93186\",\"bis\":\"93188\"},{\"von\":\"93195\",\"bis\":\"93197\"},{\"von\":\"93300\",\"bis\":\"93359\"},{\"von\":\"80788\",\"bis\":\"80788\"},{\"von\":\"94342\",\"bis\":\"94342\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Dominik Rompf<br>\n                                                                                                                                84435 Lengdorf                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491703702471\">+491703702471<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:dominik.rompf@efaflex.com\">dominik.rompf@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"10000\",\"bis\":\"10999\"},{\"von\":\"12000\",\"bis\":\"12689\"},{\"von\":\"13000\",\"bis\":\"13629\"},{\"von\":\"14000\",\"bis\":\"14199\"},{\"von\":\"14400\",\"bis\":\"14559\"},{\"von\":\"14600\",\"bis\":\"14669\"},{\"von\":\"14700\",\"bis\":\"14799\"},{\"von\":\"14800\",\"bis\":\"14829\"},{\"von\":\"14900\",\"bis\":\"14929\"},{\"von\":\"14930\",\"bis\":\"14979\"},{\"von\":\"15200\",\"bis\":\"15379\"},{\"von\":\"15500\",\"bis\":\"15569\"},{\"von\":\"15700\",\"bis\":\"15759\"},{\"von\":\"15800\",\"bis\":\"15899\"},{\"von\":\"15900\",\"bis\":\"15939\"},{\"von\":\"16200\",\"bis\":\"16359\"},{\"von\":\"16500\",\"bis\":\"16569\"},{\"von\":\"16720\",\"bis\":\"16869\"},{\"von\":\"16900\",\"bis\":\"16949\"},{\"von\":\"17000\",\"bis\":\"17509\"},{\"von\":\"18000\",\"bis\":\"18379\"},{\"von\":\"18400\",\"bis\":\"18469\"},{\"von\":\"18500\",\"bis\":\"18609\"}]'>\n                            <span class=\"htitle\">Vertriebsau\u00dfendienst<\/span>\n                                                        <p>\n                                                                    Herr Torsten Anders<br>\n                                                                                                                                15834 Rangsdorf                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491607038305\">+491607038305<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:torsten.anders@efaflex.com\">torsten.anders@efaflex.com<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                                <div class=\"flex-box-thirty standort_plz\" data-postal='[{\"von\":\"26000\",\"bis\":\"26219\"},{\"von\":\"26300\",\"bis\":\"26969\"},{\"von\":\"27200\",\"bis\":\"27449\"},{\"von\":\"27450\",\"bis\":\"27499\"},{\"von\":\"27500\",\"bis\":\"27639\"},{\"von\":\"27700\",\"bis\":\"27809\"},{\"von\":\"28000\",\"bis\":\"28359\"},{\"von\":\"28700\",\"bis\":\"28879\"},{\"von\":\"32290\",\"bis\":\"32369\"},{\"von\":\"46300\",\"bis\":\"46419\"},{\"von\":\"48000\",\"bis\":\"48369\"},{\"von\":\"48400\",\"bis\":\"48739\"},{\"von\":\"49000\",\"bis\":\"49219\"},{\"von\":\"49300\",\"bis\":\"49329\"},{\"von\":\"49340\",\"bis\":\"49849\"},{\"von\":\"59330\",\"bis\":\"59399\"}]'>\n                            <span class=\"htitle\">EFAFLEX Werksvertretung<\/span>\n                                                        <p>\n                                                                    Herr Dipl.-Wirt. Ing. (FH) Stefan K\u00f6nig<br>\n                                                                                                                                    Otto K\u00f6nig GmbH<br>\n                                                                48431 Rheine                            <\/p>\n                                                            <p>\n                                                                                                                                    <span class=\"cb-icon cb-icon-mobile\"><a href=\"tel:+491715342645\">+491715342645<\/a><\/span>\n                                                                <\/p>\n                                                                                        <p>\n                                                                    <span class=\"cb-icon cb-icon-email\"><a href=\"mailto:info@ottokoenig.de\">info@ottokoenig.de<\/a><\/span>\n                                \n                                                                <\/p>\n                                                    <\/div>\n\n                                    <\/div>\n        <\/div>\n        \n\n\n<div style=\"height:200px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":115,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-2731","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.efaflex.com\/de\/wp-json\/wp\/v2\/pages\/2731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.efaflex.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.efaflex.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.efaflex.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.efaflex.com\/de\/wp-json\/wp\/v2\/comments?post=2731"}],"version-history":[{"count":16,"href":"https:\/\/www.efaflex.com\/de\/wp-json\/wp\/v2\/pages\/2731\/revisions"}],"predecessor-version":[{"id":34014,"href":"https:\/\/www.efaflex.com\/de\/wp-json\/wp\/v2\/pages\/2731\/revisions\/34014"}],"up":[{"embeddable":true,"href":"https:\/\/www.efaflex.com\/de\/wp-json\/wp\/v2\/pages\/115"}],"wp:attachment":[{"href":"https:\/\/www.efaflex.com\/de\/wp-json\/wp\/v2\/media?parent=2731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.efaflex.com\/de\/wp-json\/wp\/v2\/categories?post=2731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.efaflex.com\/de\/wp-json\/wp\/v2\/tags?post=2731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}